{"id":39689,"date":"2023-12-13T01:03:07","date_gmt":"2023-12-13T01:03:07","guid":{"rendered":"http:\/\/lahora.mx\/?p=39689"},"modified":"2024-01-09T01:16:34","modified_gmt":"2024-01-09T01:16:34","slug":"aprueban-en-comision-del-congreso-43-leyes-de-ingresos-municipales-para-el-ejercicio-fiscal-2024","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2023\/12\/13\/aprueban-en-comision-del-congreso-43-leyes-de-ingresos-municipales-para-el-ejercicio-fiscal-2024\/","title":{"rendered":"Aprueban en Comisi\u00f3n del Congreso 43 Leyes de Ingresos Municipales para el ejercicio fiscal 2024"},"content":{"rendered":"\n<p>La Comisi\u00f3n de Hacienda y Patrimonio Municipal de la LXI Legislatura del Congreso del Estado aprob\u00f3 los dict\u00e1menes por los que se expiden las Leyes de Ingresos Municipales para el ejercicio fiscal 2024; y la Zonificaci\u00f3n Catastral y Tablas de Valores Unitarios de Suelos Urbanos y R\u00fasticos, as\u00ed como los Valores Catastrales de Construcci\u00f3n por metro cuadrado, de los 43 municipios siguientes:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Acatl\u00e1n 16. Molcaxac 31. Tochtepec<\/li>\n\n\n\n<li>Ajalpan 17. Ocoyucan 32. Tulcingo<\/li>\n\n\n\n<li>Altepexi 18. Pahuatl\u00e1n 33. Xochitl\u00e1n Todos Santos<\/li>\n\n\n\n<li>Amozoc 19. Puebla 34. Zacapala<\/li>\n\n\n\n<li>Aquixtla 20. San Andr\u00e9s Cholula 35. Zacapoaxtla<\/li>\n\n\n\n<li>Atexcal 21. San Mat\u00edas Tlalancaleca 36. Zacatl\u00e1n<\/li>\n\n\n\n<li>Atlequizay\u00e1n 22. San Pedro Cholula 37. Zapotitl\u00e1n<\/li>\n\n\n\n<li>Coronango 23. Tecamachalco 38. Zaragoza<\/li>\n\n\n\n<li>Coxcatl\u00e1n 24. Tecomatl\u00e1n 39. Zautla<\/li>\n\n\n\n<li>Coyomeapan 25. Tehuac\u00e1n 40. Zihuateutla<\/li>\n\n\n\n<li>Cuautlancingo 26. Tepatlaxco de Hidalgo 41. Zinacatepec<\/li>\n\n\n\n<li>Chignahuapan 27. Teziutl\u00e1n 42. Zongozotla<\/li>\n\n\n\n<li>Guadalupe Victoria 28. Tlachichuca 43. Zoquiapa<\/li>\n\n\n\n<li>Huauchinango 29. Tlanepantla<\/li>\n\n\n\n<li>Huejotzingo 30. Tlatlauquitepec<\/li>\n<\/ol>\n\n\n\n<p>Tras llevarse a cabo la discusi\u00f3n y el an\u00e1lisis de las reformas a las Leyes en menci\u00f3n, el \u00f3rgano colegiado aprob\u00f3 propuestas modificatorias del diputado Eduardo Alc\u00e1ntara Montiel y la diputada Lizette Minto Garc\u00eda, a las Leyes de Ingresos del Municipio de Puebla y San Pedro Cholula, respectivamente.<\/p>\n\n\n\n<p>Durante la sesi\u00f3n se cont\u00f3 con la asistencia de la tesorera del Ayuntamiento de Puebla, Mar\u00eda Isabel Garc\u00eda Ramos y el director jur\u00eddico de la Tesorer\u00eda del Ayuntamiento, Ismael Ram\u00edrez Minor, as\u00ed como de Pablo Montiel Solana, quienes asistieron para escuchar las observaciones y aclarar las dudas de las y los legisladores con relaci\u00f3n a las reformas al C\u00f3digo Fiscal y Presupuestario para este Municipio, as\u00ed como la iniciativa de Ley de Ingresos del Municipio de Puebla, para el ejercicio fiscal 2024.<\/p>\n\n\n\n<p>Una vez analizadas las reformas, las y los diputados del \u00f3rgano colegiado aprobaron el proyecto de dictamen de decreto por el que se reforman y adicionan diversas disposiciones del C\u00f3digo Fiscal y Presupuestario para el Municipio de Puebla.<\/p>\n\n\n\n<p>En m\u00e1s del orden del d\u00eda, las y los diputados integrantes del \u00f3rgano colegiado avalaron el proyecto de dictamen de decreto por virtud del cual se reforman y adicionan diversas disposiciones del Decreto del Honorable Congreso del Estado, por el que crea el Organismo P\u00fablico Descentralizado denominado \u201cCiudad Modelo\u201d.<\/p>\n\n\n\n<p>Esto, con la finalidad de que su Junta de Gobierno cuente con las atribuciones necesarias, que les permita desincorporar bienes inmuebles de dominio p\u00fablico cuando no existan razones que impongan la necesidad a conveniencia de conservarlos o cuando se justifique plenamente la necesidad del acto, por la importancia del fin al que se vayan a destinar.<\/p>\n\n\n\n<p>As\u00ed como conceder a la Junta de Gobierno del \u00d3rgano P\u00fablico Descentralizado la capacidad de autorizar las actas de dominio respectivo sobre los bienes de dominio privado.<\/p>\n\n\n\n<p>En m\u00e1s del orden del d\u00eda se aval\u00f3 el proyecto de respuesta del oficio S.A\/3480\/2023 del secretario del Ayuntamiento del Municipio de San Pedro Cholula, Puebla, por el que remite copia del Dictamen por el que se aprueba la validaci\u00f3n de los inventarios generales de los bienes municipales, correspondientes al ejercicio fiscal 2023.<\/p>\n\n\n\n<p>A la sesi\u00f3n de la Comisi\u00f3n de Hacienda asistieron las y los diputados Jorge Estefan Chidiac, Karla Victoria Mart\u00ednez Gallegos, Azucena Rosas Tapia, Fernando S\u00e1nchez Sasia, Nora Merino Escamilla, Rafael Micalco M\u00e9ndez, Lizette Minto Garc\u00eda, Eduardo Alc\u00e1ntara Montiel y Roberto Sol\u00eds Valles.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Comisi\u00f3n de Hacienda y Patrimonio Municipal de la LXI Legislatura del Congreso del Estado aprob\u00f3 los dict\u00e1menes por los que se expiden las Leyes de Ingresos Municipales para el ejercicio fiscal 2024; y la Zonificaci\u00f3n Catastral y Tablas de Valores Unitarios de Suelos Urbanos y R\u00fasticos, as\u00ed como los Valores Catastrales de Construcci\u00f3n por [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":39690,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[175],"tags":[227,223],"class_list":["post-39689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-congreso","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/39689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=39689"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/39689\/revisions"}],"predecessor-version":[{"id":39694,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/39689\/revisions\/39694"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/39690"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=39689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=39689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=39689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}