{"id":38816,"date":"2023-12-20T18:13:08","date_gmt":"2023-12-20T18:13:08","guid":{"rendered":"http:\/\/lahora.mx\/?p=38816"},"modified":"2023-12-20T18:13:09","modified_gmt":"2023-12-20T18:13:09","slug":"la-alianza-de-morena-con-expriistas-es-buenamenciona-amlo","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2023\/12\/20\/la-alianza-de-morena-con-expriistas-es-buenamenciona-amlo\/","title":{"rendered":"La alianza de Morena con expriistas es buena,menciona AMLO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El presidente Andr\u00e9s Manuel L\u00f3pez Obrador calific\u00f3 como buena la alianza de expriistas a la precampa\u00f1a de la candidata presidencial de Morena, Claudia Sheinbaum.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTodas las alianzas son buenas, cuando tienen un objetivo superior, cuan do hay por delante un ideal, un programa, cuando no nos mueve el inter\u00e9s personal por leg\u00edtimo que sea, si no nos mueve el servir a los dem\u00e1s\u201d, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En conferencia de prensa, en Acapulco, asegur\u00f3 que no importa la mala fama que tengan algunos, porque es parte de la pol\u00edtica, y la perfecci\u00f3n s\u00f3lo tiene que ver con \u201cel creador\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEso lo hacen todos los partidos en el mundo, se al\u00edan, y tambi\u00e9n los pol\u00edticos y las organizaciones sociales, es algo consustancial a la pol\u00edtica, si son buenos, son malos, si tienen mala fama o buena fama, pues eso depende de c\u00f3mo se vean las cosas. La pol\u00edtica se hace con mujeres y hombres, y la perfecci\u00f3n nada m\u00e1s tiene que ver con el creador, pero los seres humanos, todos cometemos errores\u201d, expres\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente L\u00f3pez Obrador a\u00f1adi\u00f3 que tampoco importa que algunos de los expriistas que se incorporaron a la precampa\u00f1a de Sheinbaum, tengan denuncias por corrupci\u00f3n.<br>\u201cAunque en un tiempo se hayan portado mal, pero deciden cambiar, y terminar en el \u00faltimo tramo de su vida ayudando, siendo consecuentes, pues adelante. Es la temporada, estamos en v\u00edsperas de una elecci\u00f3n y se va a estar hablando mucho de eso, y m\u00e1s porque est\u00e1 de por medio la sucesi\u00f3n presidencial\u201d, expuso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lee tambi\u00e9n: \u00abTeam Infierno\u00bb llega a equipo de Sheinbaum: se suma Sergio Mayer<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Andr\u00e9s Manuel L\u00f3pez Obrador calific\u00f3 como buena la alianza de expriistas a la precampa\u00f1a de la candidata presidencial de Morena, Claudia Sheinbaum. \u201cTodas las alianzas son buenas, cuando tienen un objetivo superior, cuan do hay por delante un ideal, un programa, cuando no nos mueve el inter\u00e9s personal por leg\u00edtimo que sea, si [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":38817,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[176],"tags":[],"class_list":["post-38816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/38816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=38816"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/38816\/revisions"}],"predecessor-version":[{"id":38818,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/38816\/revisions\/38818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/38817"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=38816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=38816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=38816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}