{"id":37659,"date":"2023-11-28T15:23:39","date_gmt":"2023-11-28T15:23:39","guid":{"rendered":"http:\/\/lahora.mx\/?p=37659"},"modified":"2023-11-28T15:23:40","modified_gmt":"2023-11-28T15:23:40","slug":"amlo-enfurece-contra-jueza-que-freno-la-extradicion-de-el-nini-a-eu","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2023\/11\/28\/amlo-enfurece-contra-jueza-que-freno-la-extradicion-de-el-nini-a-eu\/","title":{"rendered":"AMLO enfurece contra jueza que fren\u00f3 la extradici\u00f3n de \u201cEl Nini\u201d a EU"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El presidente Andr\u00e9s Manuel L\u00f3pez Obrador estall\u00f3 contra la jueza del Juzgado Cuarto de Distrito de Amparo en Materia Penal de la Ciudad de M\u00e9xico, quien otorg\u00f3 una suspensi\u00f3n a N\u00e9stor Isidro \u201cN\u201d., alias \u201cEl Nini\u201d, exjefe de seguridad de \u201cLos Chapitos\u201d en contra de su extradici\u00f3n a Estados Unidos, donde es requerido por delitos como conspiraci\u00f3n para el tr\u00e1fico de fentanilo, posesi\u00f3n de armas, entre otros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde Palacio Nacional, durante su ma\u00f1anera de este martes 28 de noviembre, en la secci\u00f3n de Cero Impunidad, se exhibi\u00f3 a la jueza Mar\u00eda del Carmen S\u00e1nchez Cisneros, quien otorg\u00f3 la protecci\u00f3n de la justicia al presunto narcotraficante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSe detiene en este caso a N\u00e9stor Isidro, y una jueza casi al momento de la detenci\u00f3n le ofrece el amparo para que no sea extraditado. \u00bfQu\u00e9 es eso? Si esto no es corrupci\u00f3n, que me digan los ministros de la Corte y el Consejo de la Judicatura, de qu\u00e9 se trata. Esto no es derecho, esto es chueco\u201d, espet\u00f3 el mandatario federal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue la tarde del jueves 23 de noviembre cuando la jueza del Juzgado Cuarto de Distrito de Amparo en Materia Penal de la Ciudad de M\u00e9xico detall\u00f3 que la suspensi\u00f3n provisional \u00fanicamente tendr\u00e1 efecto para la orden de extradici\u00f3n emitida por las autoridades estadounidenses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSe concede la suspensi\u00f3n de oficio y de plano para el efecto de que las cosas se mantengan en el estado que guardan y no se ejecute la extradici\u00f3n del directo quejoso\u201d, dict\u00f3 la resoluci\u00f3n de la juzgadora.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Andr\u00e9s Manuel L\u00f3pez Obrador estall\u00f3 contra la jueza del Juzgado Cuarto de Distrito de Amparo en Materia Penal de la Ciudad de M\u00e9xico, quien otorg\u00f3 una suspensi\u00f3n a N\u00e9stor Isidro \u201cN\u201d., alias \u201cEl Nini\u201d, exjefe de seguridad de \u201cLos Chapitos\u201d en contra de su extradici\u00f3n a Estados Unidos, donde es requerido por delitos [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":37660,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[176],"tags":[195],"class_list":["post-37659","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-principal"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/37659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=37659"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/37659\/revisions"}],"predecessor-version":[{"id":37661,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/37659\/revisions\/37661"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/37660"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=37659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=37659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=37659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}