{"id":36132,"date":"2023-10-01T00:12:44","date_gmt":"2023-10-01T00:12:44","guid":{"rendered":"http:\/\/lahora.mx\/?p=36132"},"modified":"2023-10-31T00:14:01","modified_gmt":"2023-10-31T00:14:01","slug":"presentan-iniciativa-en-el-congreso-para-sancionar-la-exposicion-de-animales-a-la-quema-de-pirotecnia","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2023\/10\/01\/presentan-iniciativa-en-el-congreso-para-sancionar-la-exposicion-de-animales-a-la-quema-de-pirotecnia\/","title":{"rendered":"Presentan iniciativa en el Congreso para sancionar la exposici\u00f3n de animales a la quema de pirotecnia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Para contemplar como infracciones y sancionar conforme a lo establecido en los ordenamientos jur\u00eddicos aplicables, el exponer a los animales a la quema de artificios o fuegos pirot\u00e9cnicos o explosivos, que alteren su comportamiento, gener\u00e1ndoles estr\u00e9s, cualquier otro tipo de sufrimiento o, como consecuencia de ello, la p\u00e9rdida de la vida, el diputado Jos\u00e9 Antonio L\u00f3pez Ruiz present\u00f3 una iniciativa de reforma a las fracciones XX, XXI y la adici\u00f3n de la XXII al art\u00edculo 18 de la Ley de Bienestar Animal del Estado de Puebla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante sesi\u00f3n ordinaria de la LXI Legislatura del Congreso del Estado, la Mesa Directiva dio cuenta de la iniciativa del diputado, en la cual se\u00f1ala que uno de los retos a afrontar en materia de bienestar animal es la erradicaci\u00f3n del uso de la pirotecnia, que causa afectaciones a la salud de los animales, en particular de su o\u00eddo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La iniciativa fue turnada a la Comisi\u00f3n de Medio Ambiente, Recursos Naturales y Cambio Clim\u00e1tico para su estudio y resoluci\u00f3n procedente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De igual forma, la Mesa Directiva dio cuenta de la iniciativa del diputado Jos\u00e9 Antonio L\u00f3pez Ruiz para reformar las fracciones XII, XIII y adicionar la XIV al art\u00edculo 14 de la Ley de Seguridad P\u00fablica, a fin de se\u00f1alar que, al Sistema de Seguridad P\u00fablica del Estado, le corresponde dise\u00f1ar y ejecutar pol\u00edticas de integridad, \u00e9tica y responsabilidad, en la actividad de las instituciones policiales, para fortalecer la proximidad entre estas y la sociedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La iniciativa fue turnada a la Comisi\u00f3n de Seguridad P\u00fablica para su estudio y resoluci\u00f3n procedente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En otro momento de la sesi\u00f3n, la diputada Yolanda G\u00e1mez Mendoza present\u00f3 una iniciativa de reforma a la fracci\u00f3n XXVI del art\u00edculo 380 del C\u00f3digo Penal del Estado, con el objetivo de considerar como agravante del delito de robo cuando se cometa dentro de instituciones art\u00edsticas o culturales, as\u00ed como en bibliotecas o museos y sean sustra\u00eddos bienes muebles destinados a las actividades y exposiciones que en los mismos se ofrecen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La iniciativa fue turnada a la Comisi\u00f3n de Procuraci\u00f3n y Administraci\u00f3n de Justicia para su estudio y resoluci\u00f3n procedente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, el diputado Gerardo Hern\u00e1ndez Rojas present\u00f3 una iniciativa de reforma a diversas disposiciones de la Ley de los Trabajadores al Servicio del Estado a fin de establecer un l\u00edmite en el c\u00e1lculo de los sueldos ca\u00eddos, en armon\u00eda con lo dispuesto en el art\u00edculo 48 de la Ley Federal del Trabajo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto para establecer que, si en el juicio correspondiente no se comprueba por el patr\u00f3n la causa de la rescisi\u00f3n, el trabajador tendr\u00e1 derecho, adem\u00e1s, cualquiera que hubiese sido la acci\u00f3n intentada, a que se le paguen los salarios vencidos computados desde la fecha del despido hasta por un per\u00edodo m\u00e1ximo de doce meses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La iniciativa fue turnada a la Comisi\u00f3n de Trabajo, Competitividad y Previsi\u00f3n Social para su estudio y resoluci\u00f3n procedente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la sesi\u00f3n, la Mesa Directiva dio cuenta de la iniciativa de la diputada Laura Zapata Mart\u00ednez para reformar el art\u00edculo 57 de la Constituci\u00f3n del Estado, a fin de armonizarla con la Constituci\u00f3n Mexicana para establecer que sea facultad del Congreso expedir leyes que establezcan la coordinaci\u00f3n de la entidad y los municipios, en materia de derechos de ni\u00f1as, ni\u00f1os y adolescentes, velando en todo momento por el inter\u00e9s superior de los mismos, as\u00ed como en materia de formaci\u00f3n y desarrollo integral de la juventud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La iniciativa fue turnada a la Comisi\u00f3n de Gobernaci\u00f3n y Puntos Constitucionales para su an\u00e1lisis y dictaminaci\u00f3n correspondiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Mesa Directiva tambi\u00e9n dio cuenta de la iniciativa de la diputada Patricia Valencia \u00c1vila para adicionar un \u00faltimo p\u00e1rrafo al art\u00edculo 47 de la Ley de Desarrollo Rural Sustentable, a fin de establecer que, para efecto de los cambios tecnol\u00f3gicos y de procesos, deber\u00e1 de procurarse, que los mismos no da\u00f1en o alteren el medio ambiente, la atm\u00f3sfera, el agua, el suelo y\/o el ciclo hidrol\u00f3gico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La iniciativa fue enviada a la Comisi\u00f3n de Desarrollo Rural para su estudio y resoluci\u00f3n procedente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para contemplar como infracciones y sancionar conforme a lo establecido en los ordenamientos jur\u00eddicos aplicables, el exponer a los animales a la quema de artificios o fuegos pirot\u00e9cnicos o explosivos, que alteren su comportamiento, gener\u00e1ndoles estr\u00e9s, cualquier otro tipo de sufrimiento o, como consecuencia de ello, la p\u00e9rdida de la vida, el diputado Jos\u00e9 Antonio [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":36133,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[175],"tags":[227,223],"class_list":["post-36132","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-congreso","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/36132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=36132"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/36132\/revisions"}],"predecessor-version":[{"id":36134,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/36132\/revisions\/36134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/36133"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=36132"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=36132"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=36132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}