{"id":35047,"date":"2023-10-10T18:20:04","date_gmt":"2023-10-10T18:20:04","guid":{"rendered":"http:\/\/lahora.mx\/?p=35047"},"modified":"2023-10-10T18:20:05","modified_gmt":"2023-10-10T18:20:05","slug":"mas-de-mil-500-muertos-y-6-mil-heridos-en-la-guerra-israel-hamas-segun-la-onu","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2023\/10\/10\/mas-de-mil-500-muertos-y-6-mil-heridos-en-la-guerra-israel-hamas-segun-la-onu\/","title":{"rendered":"M\u00e1s de mil 500 muertos y 6 mil heridos en la guerra Israel-Ham\u00e1s, seg\u00fan la ONU"},"content":{"rendered":"\n<p>M\u00e1s de mil 500 personas han muerto en la guerra entre Israel y Hamas, con unos 6 mil 400 heridos en total, dijo hoy un portavoz de la Oficina de Coordinaci\u00f3n de Ayuda Humanitaria de Naciones Unidas (OCHA).<\/p>\n\n\n\n<p>Informes de Israel indican que m\u00e1s de 900 nacionales de este pa\u00eds y extranjeros han muerto y que los heridos superan los 2 mil 600, mientras, por su parte, el Ministerio de Salud de Gaza ha comunicado la muerte de 687 palestinos y m\u00e1s de 3 mil 800 heridos, a los que se deben sumar aquellos que han perecido en combates en territorio israel\u00ed.<\/p>\n\n\n\n<p>Adem\u00e1s, se ha reportado la muerte de otros 17 palestinos, incluidos cuatro ni\u00f1os, en Cisjordania, donde se han registrado 295 heridos.<\/p>\n\n\n\n<p>El portavoz de OCHA, Jens Laerke, inform\u00f3 en Ginebra que el n\u00famero de desplazados en Gaza ha aumentado considerablemente en las \u00faltimas 24 horas superando los 187 mil.<\/p>\n\n\n\n<p>Se da por descontado que este n\u00famero subir\u00e1 en las pr\u00f3ximas horas y que el volumen de desplazamiento depender\u00e1 del tiempo que duren las hostilidades.<br>M\u00e1s de 137 mil desplazados por guerra Israel-Hamas se refugian en escuelas<br>Unos 137 mil 500 desplazados est\u00e1n refugiados en 83 escuelas de la Agencia de Naciones Unidas para los Refugiados Palestinos (UNRWA), donde las condiciones son extremadamente precarias y el suministro de agua potable es muy limitado, indic\u00f3 el organismo.<\/p>\n\n\n\n<p>En coordinaci\u00f3n con otra agencia humanitaria de la ONU se ha podido distribuir pan entre los desplazados.<\/p>\n\n\n\n<p>La directora de Comunicaciones de la UNRWA, Tamara Alrifai, explic\u00f3 por videollamada desde Am\u00e1n que de todas las escuelas donde las familias palestinas han buscado refugio, solo 54 estaban habilitadas para este fin en caso de emergencia y que el n\u00famero de personas que necesitan cobijo supera ampliamente la capacidad que tienen.<\/p>\n\n\n\n<p>Record\u00f3 que esta crisis, la m\u00e1s violenta al menos desde 2008, ha surgido en momentos en que las finanzas del organismo creado para asistir a los refugiados palestinos est\u00e1n debilitadas por la reducci\u00f3n de las contribuciones de los Estados.<\/p>\n\n\n\n<p>\u00abNo tenemos los recursos adecuados para responder a una situaci\u00f3n de esta magnitud\u00bb, recalc\u00f3, tras recordar que de los 2.2 millones de residentes de Gaza, 1.7 millones son refugiados para quienes la UNRWA es un salvavidas del que dependen para pr\u00e1cticamente todo.<\/p>\n\n\n\n<p>Alrifai indic\u00f3 que 18 colegios del organismo han sido da\u00f1ados en los ataques de Israel contra Gaza, entre los cuales se encuentra un establecimiento especializado para ni\u00f1os con problemas de visi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de mil 500 personas han muerto en la guerra entre Israel y Hamas, con unos 6 mil 400 heridos en total, dijo hoy un portavoz de la Oficina de Coordinaci\u00f3n de Ayuda Humanitaria de Naciones Unidas (OCHA). Informes de Israel indican que m\u00e1s de 900 nacionales de este pa\u00eds y extranjeros han muerto y [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":35048,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[183],"tags":[],"class_list":["post-35047","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/35047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=35047"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/35047\/revisions"}],"predecessor-version":[{"id":35049,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/35047\/revisions\/35049"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/35048"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=35047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=35047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=35047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}