{"id":35041,"date":"2023-10-10T17:47:32","date_gmt":"2023-10-10T17:47:32","guid":{"rendered":"http:\/\/lahora.mx\/?p=35041"},"modified":"2023-10-10T17:47:33","modified_gmt":"2023-10-10T17:47:33","slug":"bancada-pt-puebla-pasa-la-prueba-historica","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2023\/10\/10\/bancada-pt-puebla-pasa-la-prueba-historica\/","title":{"rendered":"Bancada PT Puebla pasa la prueba hist\u00f3rica"},"content":{"rendered":"\n<p>Al acudir al Segundo Informe de Labores de los diputados locales del Partido del Trabajo (PT), el gobernador Sergio C\u00e9spedes Peregrina asegur\u00f3 que la bancada pas\u00f3 una prueba hist\u00f3rica al no dejarse presionar por intereses electorales a nivel nacional, y demostrar que en Puebla las decisiones las toman los poblanos.<\/p>\n\n\n\n<p>Durante un evento en el Centro de Convenciones, donde tambi\u00e9n estuvo presente la gobernadora de Tlaxcala, Lorena Cuellar, las diputadas Nora Merino Escamilla, M\u00f3nica Silva Ruiz, Antonio L\u00f3pez Ruiz, Miguel Huerta Rodr\u00edguez, Gerardo Hern\u00e1ndez Rojas, este \u00faltimo con solo cuatro meses en funciones, ya que supli\u00f3 al fallecido Mariano Hern\u00e1ndez Reyes, el gobernador record\u00f3 los hechos del mes de diciembre cuando se dio la presi\u00f3n nacional.<\/p>\n\n\n\n<p>Indic\u00f3 que los legisladores no se dejaron llevar por las corrientes partidistas nacionales, y actuaron con responsabilidad ya que en Puebla las decisiones las toman los poblanos.<\/p>\n\n\n\n<p>Destac\u00f3 el trabajo que han realizado en los dos a\u00f1os de la legislatura presentando reformas que le favorecen a Puebla y los poblanos, trabajando con las dem\u00e1s bancadas.<\/p>\n\n\n\n<p>Finalmente, afirm\u00f3 que los legisladores no defraudaron el voto que les dieron los poblanos.<\/p>\n\n\n\n<p>En su mensaje conjunto los legisladores se\u00f1alaron que han presentado 102 iniciativas en conjunto que tienen que ver en contra de la violencia hacia las mujeres, apoyo al campo, desarrollo de los municipios.<\/p>\n\n\n\n<p>Adem\u00e1s, a trav\u00e9s de la gesti\u00f3n, han atendido a 123,826 personas con diversos tr\u00e1mites o apoyos, siendo de las bancadas en conjunto que mayor contacto tiene con los sectores de la sociedad.<\/p>\n\n\n\n<p>El coordinador de los legisladores, Antonio L\u00f3pez Ruiz, expreso que se han mantenido unidos y apoyando de frente la transformaci\u00f3n del estado.<\/p>\n\n\n\n<p>Nora Merino Escamilla se\u00f1al\u00f3 que el PT es una fuerza real que ha trabajado con responsabilidad, y destac\u00f3 que sus propuestas han sido a favor de las mujeres.<\/p>\n\n\n\n<p>La diputada M\u00f3nica Silva Ruiz destac\u00f3 que en la legislatura se han tenido importantes avances al haberse aprobado reformas al C\u00f3digo Penal, como la Ley Monz\u00f3n, Ley \u00c1cida, y otras que incluso se van a copiar en otros estados y pa\u00edses, siendo la bancada del PT una parte importante en las propuestas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al acudir al Segundo Informe de Labores de los diputados locales del Partido del Trabajo (PT), el gobernador Sergio C\u00e9spedes Peregrina asegur\u00f3 que la bancada pas\u00f3 una prueba hist\u00f3rica al no dejarse presionar por intereses electorales a nivel nacional, y demostrar que en Puebla las decisiones las toman los poblanos. Durante un evento en el [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":35042,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[175],"tags":[223],"class_list":["post-35041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/35041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=35041"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/35041\/revisions"}],"predecessor-version":[{"id":35043,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/35041\/revisions\/35043"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/35042"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=35041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=35041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=35041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}