{"id":35005,"date":"2023-10-09T21:30:46","date_gmt":"2023-10-09T21:30:46","guid":{"rendered":"http:\/\/lahora.mx\/?p=35005"},"modified":"2023-10-09T21:30:47","modified_gmt":"2023-10-09T21:30:47","slug":"paridad-de-genero-modificara-decisiones-para-elecciones-2024-eduardo-rivera","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2023\/10\/09\/paridad-de-genero-modificara-decisiones-para-elecciones-2024-eduardo-rivera\/","title":{"rendered":"Paridad de G\u00e9nero modificar\u00e1 decisiones para elecciones 2024: Eduardo Rivera"},"content":{"rendered":"\n<p>La resoluci\u00f3n del Instituto Nacional Electoral (INE) sobre la implementaci\u00f3n de la paridad de g\u00e9nero en el proceso electoral del 2024 modificar\u00eda las decisiones que hasta el momento han tomado los partidos pol\u00edticos para designar las candidaturas estatales, asegur\u00f3 el alcalde Eduardo Rivera P\u00e9rez.<\/p>\n\n\n\n<p>Bajo ese contexto se encuentra Morena, ya que es el \u00fanico partido que ha impulsado a trav\u00e9s de su Consejo Estatal a cuatro perfiles en Puebla, dos hombres \u2013Julio Huerta G\u00f3mez e Ignacio Mier Velazco- y dos mujeres- Olivia Salom\u00f3n Vibaldo y Lizeth S\u00e1nchez Garc\u00eda-, sin que hasta el momento el INE haya determinado si Puebla tendr\u00e1 que designar una gobernadora.<\/p>\n\n\n\n<p>\u00abYa que ser\u00e1 la propia autoridad electoral quien emita en qu\u00e9 estados en los que se registrar\u00e1n elecciones deben asignarse mujeres y hombres para buscar la candidatura. La sesi\u00f3n del INE a verificarse este lunes ser\u00e1 determinante para conocer el camino que deba tomar el proceso del 2024,\u00bb opin\u00f3 en entrevista el presidente municipal.<\/p>\n\n\n\n<p>En los ocho estados donde se renovar\u00e1n gubernaturas y la jefatura de la Ciudad de M\u00e9xico, las Comisiones Unidas de Prerrogativas y Partidos y de Igualdad de G\u00e9nero y No discriminaci\u00f3n del INE, buscar\u00e1n impulsar este lunes 9 de octubre, que en cinco sean mujeres y en cuatro, hombres.<\/p>\n\n\n\n<p>Las declaraciones del presidente municipal, quien en los \u00faltimos d\u00edas ha afirmado que ser\u00e1 hasta finales de a\u00f1o cuando solicite licencia al cargo y determine la posici\u00f3n en la que participar\u00e1, se dan en el contexto de que Morena cuenta hasta el momento con cuatro perfiles aprobados por su Consejo Estatal, de los cuales dos son el ex secretario de Gobernaci\u00f3n Julio Huerta G\u00f3mez y el diputado federal Ignacio Mier Velazco.<\/p>\n\n\n\n<p>Mientras que las otras dos mujeres son las ex secretarias de Finanzas y de Bienestar, respectivamente, Olivia Salom\u00f3n Vivaldo y Lizeth S\u00e1nchez Garc\u00eda.<\/p>\n\n\n\n<p>Una vez que las Comisiones Unidas de Prerrogativas y Partidos y de Igualdad de G\u00e9nero y No discriminaci\u00f3n en su caso logren este d\u00eda la aprobaci\u00f3n del anteproyecto en el que se prev\u00e9 la distribuci\u00f3n de cinco candidaturas para mujeres y cuatro para hombres para los nueve estados, esta ser\u00e1 sometida al pleno del Consejo General del INE.<\/p>\n\n\n\n<p>Ante lo cual, el propio presidente municipal Eduardo Rivera P\u00e9rez asegur\u00f3 celebrar que se impulse a las mujeres como protagonistas del proceso electoral rumbo al 2024.<br>Por otro lado, Rivera P\u00e9rez confirm\u00f3 que el hecho de violencia registrado en inmediaciones de una sucursal OXXO ubicada en Xonaca s\u00ed fue a causa de una ri\u00f1a entre particulares y que fueron 4 las personas involucradas de las cuales una falleci\u00f3 por las lesiones y una m\u00e1s se encuentra en hospitalizaci\u00f3n.<\/p>\n\n\n\n<p>Afirm\u00f3 que la Polic\u00eda Municipal remitir\u00e1 los datos y las pruebas correspondientes ante el Ministerio P\u00fablico, a fin de dar con el paradero de los responsables.<\/p>\n\n\n\n<p>Ser\u00e1 la propia Fiscal\u00eda General del Estado quien contin\u00fae a cargo de las investigaciones y la aprehensi\u00f3n de los presuntos responsables, as\u00ed como, en su caso, de imputar los delitos correspondientes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La resoluci\u00f3n del Instituto Nacional Electoral (INE) sobre la implementaci\u00f3n de la paridad de g\u00e9nero en el proceso electoral del 2024 modificar\u00eda las decisiones que hasta el momento han tomado los partidos pol\u00edticos para designar las candidaturas estatales, asegur\u00f3 el alcalde Eduardo Rivera P\u00e9rez. Bajo ese contexto se encuentra Morena, ya que es el \u00fanico [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":35006,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[175],"tags":[223],"class_list":["post-35005","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/35005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=35005"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/35005\/revisions"}],"predecessor-version":[{"id":35007,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/35005\/revisions\/35007"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/35006"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=35005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=35005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=35005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}