{"id":34172,"date":"2023-09-28T16:48:13","date_gmt":"2023-09-28T16:48:13","guid":{"rendered":"http:\/\/lahora.mx\/?p=34172"},"modified":"2023-09-28T16:48:14","modified_gmt":"2023-09-28T16:48:14","slug":"mas-de-30-kilos-de-droga-son-asegurados-en-la-central-camionera-de-puebla","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2023\/09\/28\/mas-de-30-kilos-de-droga-son-asegurados-en-la-central-camionera-de-puebla\/","title":{"rendered":"M\u00e1s de 30 kilos de droga son asegurados en la central camionera de Puebla"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Alberto N, de 48 a\u00f1os de edad fue detenido en la capital de Puebla por elementos de la Secretar\u00eda de Seguridad Ciudadana (SSC) por su probable participaci\u00f3n en delitos contra la salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Polic\u00edas Municipales adscritos a la Unidad Canina efectuaban un patrullaje preventivo al interior de una central camionera, ubicada en la colonia Las Cuartillas, cuando un ejemplar canino especializado en la detecci\u00f3n de narc\u00f3ticos modific\u00f3 su conducta frente a dos maletas, propiedad de un individuo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras implementar los protocolos correspondientes y las respectivas medidas de seguridad, los elementos hallaron al interior del equipaje 32 empaques que almacenaban hierba verde y que desprend\u00edan un olor caracter\u00edstico a la droga conocida como marihuana, cuyo peso en total superaba los 30 kilogramos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por lo anterior, el hombre fue detenido y puesto a disposici\u00f3n del Ministerio P\u00fablico para dar inicio a las investigaciones a que haya lugar. (AD)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alberto N, de 48 a\u00f1os de edad fue detenido en la capital de Puebla por elementos de la Secretar\u00eda de Seguridad Ciudadana (SSC) por su probable participaci\u00f3n en delitos contra la salud. Polic\u00edas Municipales adscritos a la Unidad Canina efectuaban un patrullaje preventivo al interior de una central camionera, ubicada en la colonia Las Cuartillas, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":34173,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[175,226],"tags":[223],"class_list":["post-34172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","category-policia","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/34172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=34172"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/34172\/revisions"}],"predecessor-version":[{"id":34174,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/34172\/revisions\/34174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/34173"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=34172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=34172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=34172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}