{"id":33505,"date":"2023-09-18T00:34:05","date_gmt":"2023-09-18T00:34:05","guid":{"rendered":"http:\/\/lahora.mx\/?p=33505"},"modified":"2023-09-18T00:34:05","modified_gmt":"2023-09-18T00:34:05","slug":"explota-tanque-de-gas-dejando-sin-hogar-a-familia-en-san-jeronimo-caleras","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2023\/09\/18\/explota-tanque-de-gas-dejando-sin-hogar-a-familia-en-san-jeronimo-caleras\/","title":{"rendered":"Explota tanque de gas dejando sin hogar a familia en San Jer\u00f3nimo Caleras"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Una familia lo perdi\u00f3 todo luego de que la casa improvisada con cart\u00f3n y l\u00e1minas donde viv\u00edan ardi\u00f3 en llamas la ma\u00f1ana de este domingo en la junta auxiliar de San Jer\u00f3nimo Caleras. El siniestro se origin\u00f3 por la explosi\u00f3n de un tanque de gas y por fortuna, ninguna persona result\u00f3 lesionada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin nada material es como se qued\u00f3 una familia de tres integrantes luego de que el domicilio en el que viv\u00edan se incendi\u00f3 mientras ellos acudieron a realizar algunas compras en la junta auxiliar de San Jer\u00f3nimo Caleras en Puebla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue poco antes de las 09:00 horas de este d\u00eda que los cuerpos de emergencia fueron solicitados a la calle 20 de noviembre debido a que una casa estaba siendo consumida por las llamas. Los vecinos del lugar informaron que previo al fuego escucharon un fuerte estallido que los hizo salir de sus viviendas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras la llegada de los cuerpos de emergencia se inform\u00f3 que se trat\u00f3 de la explosi\u00f3n de un tanque de gas de 20 kilos y habr\u00eda sido una fuga lo que caus\u00f3 que \u00e9ste estallara para posteriormente originarse un voraz incendio que r\u00e1pidamente consumi\u00f3 el inmueble improvisado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con base en lo argumentado por personal de emergencias que labor\u00f3 en el lugar, ninguna persona se encontraba adentro al momento del accidente, por lo que se descart\u00f3 que hubiera personas lesionadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hasta el cierre de esta edici\u00f3n, los habitantes de la casa -un matrimonio- no han podido ser localizados ya que, a decir de los vecinos, salieron desde temprano a realizar unas compras.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una familia lo perdi\u00f3 todo luego de que la casa improvisada con cart\u00f3n y l\u00e1minas donde viv\u00edan ardi\u00f3 en llamas la ma\u00f1ana de este domingo en la junta auxiliar de San Jer\u00f3nimo Caleras. El siniestro se origin\u00f3 por la explosi\u00f3n de un tanque de gas y por fortuna, ninguna persona result\u00f3 lesionada. Sin nada material [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":33511,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-33505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/33505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=33505"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/33505\/revisions"}],"predecessor-version":[{"id":33512,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/33505\/revisions\/33512"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/33511"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=33505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=33505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=33505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}