{"id":30937,"date":"2023-08-06T22:04:45","date_gmt":"2023-08-06T22:04:45","guid":{"rendered":"http:\/\/lahora.mx\/?p=30937"},"modified":"2023-08-06T22:04:46","modified_gmt":"2023-08-06T22:04:46","slug":"congreso-del-estado-participa-en-ambicioso-plan-de-reforestacion-encabezado-por-la-diputada-xel-hernandez","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2023\/08\/06\/congreso-del-estado-participa-en-ambicioso-plan-de-reforestacion-encabezado-por-la-diputada-xel-hernandez\/","title":{"rendered":"Congreso del Estado participa en ambicioso plan de reforestaci\u00f3n encabezado por la diputada Xel Hern\u00e1ndez"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Bajo el lema \u201cSalvemos La Malinche\u201d, este s\u00e1bado 5 de agosto el Congreso del Estado de Puebla particip\u00f3 en la reforestaci\u00f3n de la zona boscosa de San Miguel Espejo, al norte de la capital poblana, en la que se sembraron 3,500 plantas de especies end\u00e9micas de esta regi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Diputada del Distrito 11, Xel Arianna Hern\u00e1ndez Garc\u00eda, fue encargada por parte de la LXI Legislatura para organizar esta actividad en representaci\u00f3n del Diputado Presidente, Eduardo Castillo L\u00f3pez, como parte de la Jornada Nacional de Reforestaci\u00f3n que se llev\u00f3 a cabo en esta junta auxiliar del municipio de Puebla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Junto con m\u00e1s de 200 participantes de diferentes organizaciones de la sociedad civil, ciudadanos y habitantes de la comunidad, Xel Arianna Hern\u00e1ndez destac\u00f3 el papel activo de las juventudes poblanas preocupadas por la conservaci\u00f3n del medio ambiente del volc\u00e1n La Malinche, que es una de las \u00c1reas Naturales Protegidas m\u00e1s deforestada del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Diputada Local recalc\u00f3 que cada uno de los nuevos \u00e1rboles plantados este fin de semana representa un compromiso con el futuro de la capital poblana, pues se trata de garantizar mejores condiciones del aire y, al mismo tiempo, m\u00e1s captaci\u00f3n de agua con los futuros bosques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Xel Arianna Hern\u00e1ndez agreg\u00f3 que La Malinche est\u00e1 recibiendo una fuerte presi\u00f3n urbana a lo que se suma la tala ilegal por medio de grupos organizados, que est\u00e1n causando un grave da\u00f1o ambiental. De ah\u00ed la importancia de las acciones coordinadas entre los diferentes niveles de gobierno y sociedad, para revertir esta situaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Federaci\u00f3n declar\u00f3 a La Malinche como una \u00c1rea Natural Protegida en 1938, y la actual administraci\u00f3n del Gobierno del Estado de Puebla, a trav\u00e9s de la Secretar\u00eda de Medio Ambiente, Desarrollo Urbano y Ordenamiento Territorial, est\u00e1 llevando a cabo la reforestaci\u00f3n de m\u00e1s de 12 hect\u00e1reas con plantas de pino, oyamel y encino, que son end\u00e9micas de las inmediaciones de este volc\u00e1n, y don\u00f3 las 3,500 plantas sembradas el s\u00e1bado en esta jornada de reforestaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bajo el lema \u201cSalvemos La Malinche\u201d, este s\u00e1bado 5 de agosto el Congreso del Estado de Puebla particip\u00f3 en la reforestaci\u00f3n de la zona boscosa de San Miguel Espejo, al norte de la capital poblana, en la que se sembraron 3,500 plantas de especies end\u00e9micas de esta regi\u00f3n. La Diputada del Distrito 11, Xel Arianna [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30938,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[175],"tags":[227,223],"class_list":["post-30937","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-congreso","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/30937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=30937"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/30937\/revisions"}],"predecessor-version":[{"id":30939,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/30937\/revisions\/30939"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/30938"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=30937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=30937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=30937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}