{"id":30811,"date":"2023-08-04T00:24:20","date_gmt":"2023-08-04T00:24:20","guid":{"rendered":"http:\/\/lahora.mx\/?p=30811"},"modified":"2023-08-04T00:24:21","modified_gmt":"2023-08-04T00:24:21","slug":"llibros-de-texto-de-la-sep-no-se-distribuiran-en-estos-estados","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2023\/08\/04\/llibros-de-texto-de-la-sep-no-se-distribuiran-en-estos-estados\/","title":{"rendered":"Llibros de texto de la SEP no se distribuir\u00e1n en estos estados"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Todav\u00eda no inicia el ciclo escolar 2023-2024 y ya hay discusiones sobre los contenidos en los libros de texto gratuitos, los cuales han sido criticados por el Partido Acci\u00f3n Nacional (PAN), cuyo l\u00edder, Marko Cort\u00e9s, ha propuesto destruirlos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n asociaciones de padres han hecho se\u00f1alamientos sobre la poca ense\u00f1anza sobre matem\u00e1ticas, y algunas voces se han escandalizado por los contenidos de educaci\u00f3n sexual en los libros para ni\u00f1as y ni\u00f1os de grados avanzados de primaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En varios estados del pa\u00eds, gobernadoras, gobernadores y autoridades educativas se han pronunciado en contra de los libros de texto gratuitos de la Secretar\u00eda de Educaci\u00f3n P\u00fablica (SEP).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los estados en contra de los libros de la SEP<br>Maru Campos ordena frenar la entrega de ejemplares<br>La gobernadora de Chihuahua, Maru Campos, orden\u00f3 detener la distribuci\u00f3n de nuevos libros de texto en Chihuahua, siguiendo el ejemplo de Guanajuato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La misteriosa muerte de peces en Sinaloa: Esto es lo que sabemos<br>Miles de peces muertos fueron hallados en playas de Sinaloa. (Foto: Coepriss)<br>Y el presidente de la Coparmex Chihuahua, Salvador Carrejo Orozco, aval\u00f3 la orden de una juez a la SEP que suspenda la distribuci\u00f3n de los libros de texto gratuitos por considerarlos \u201cuna imposici\u00f3n para el adoctrinamiento de la 4T\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Guanajuato \u2018resguarda\u2019 los libros<br>Guanajuato embodeg\u00f3 los nuevos libros de texto de la SEP, en acato de la suspensi\u00f3n definitiva concedida a la Uni\u00f3n Nacional de Padres de Familia por una jueza federal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Secretar\u00eda de Educaci\u00f3n de Guanajuato inform\u00f3 que hab\u00eda recibido el 35.9 por ciento de los nuevos libros de texto gratuitos, los cuales fueron distribuidos en algunos planteles, aunque desde la semana pasada personal de las escuelas los regres\u00f3 a las bodegas por \u00f3rdenes de esa dependencia estatal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLos libros que llegan los estamos resguardando en almacenes regionales, hasta en tanto lleguen la totalidad y la SEP resuelva el tema legal que enfrenta\u201d, detall\u00f3 la dependencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jalisco embodega los libros<br>Hay m\u00e1s de un mill\u00f3n de libros de texto embodegados en Jalisco, debido a un amparo que impide que se distribuyan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A la entidad ya llegaron dos terceras partes de los libros asignados para nivel b\u00e1sico, mientras que el secretario de Educaci\u00f3n local inform\u00f3 que los que siguen por llegar tambi\u00e9n se van a embodegar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstamos hablando de varios millones, estamos hablando de los libros de 1.6 millones de alumnos\u201d dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n dijo que se pondr\u00e1 especial atenci\u00f3n al tema de las ideolog\u00edas pol\u00edtico social: \u201cla parte ideol\u00f3gica, evidentemente, nos parece que en educaci\u00f3n b\u00e1sica no tiene que estar presente, lo que tenemos que estar ense\u00f1ando en preescolar, primaria y secundaria es un an\u00e1lisis cr\u00edtico de la historia de manera neutral, cient\u00edfica, no hace falta decirles cu\u00e1l es el mejor modelo econ\u00f3mico, se necesita analizar los distintos modelos y despu\u00e9s emitir una opini\u00f3n personal\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello, agreg\u00f3 que entre los temas pol\u00e9micos destaca la \u2018descolonizaci\u00f3n\u2019, \u201cno s\u00e9 cu\u00e1ntos de nosotros nos sentimos atados a Espa\u00f1a, somos claramente una naci\u00f3n mestiza, muy rica y hay que favorecer el entorno para todos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los estados que han defendido los libros de texto<br>Gobernadores y gobernadoras de Morena ya salieron en defensa de la distribuci\u00f3n de libros y criticaron el llamado del PAN a destruirlos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Incluso, compararon a Marko Cort\u00e9s con Adolfo Hitler, quien fuera l\u00edder del nazismo, y con el dictador chileno Augusto Pinochet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, afirmaron que el PAN se est\u00e1 oponiendo al desarrollo integral de ni\u00f1as y ni\u00f1os para mantener al pueblo ignorante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLas gobernadoras, gobernadores y el jefe de Gobierno nos pronunciamos en apoyo a la distribuci\u00f3n del libro de texto en todas las primarias del pa\u00eds, por el futuro promisorio de nuestra ni\u00f1ez, \u00a1que nadie se quede sin libros!\u201d, dijeron.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El texto fue firmado por Marina del Pilar \u00c1vila (Baja California); Rutilio Escand\u00f3n (Chiapas), Evelyn Salgado (Guerrero), Cuauht\u00e9moc Blanco (Morelos), Sergio Salom\u00f3n C\u00e9spedes (Puebla), Rub\u00e9n Rocha Moya (Sinaloa), Am\u00e9rico Villareal (Tamaulipas), V\u00edctor Manuel Castro Cos\u00edo (BCS), Mart\u00ed Batres (CDMX), Julio Menchaca (Hidalgo), Miguel \u00c1ngel Navarro (Nayarit), Mara Lezama (Quintana Roo), Alfonso Durazo (Sonora), Lorena Cu\u00e9llar (Tlaxcala), David Monreal (Zacatecas).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed como por Layda Sansores (Campeche), Indira Vizca\u00edno (Colima), Alfredo Ram\u00edrez Bedolla (Michoac\u00e1n), Salom\u00f3n Jara (Oaxaca), Ricardo Gallardo (San Luis Potos\u00ed), Carlos Manuel Merino (Tabasco) y Cuitl\u00e1huac Garc\u00eda (Veracruz).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todav\u00eda no inicia el ciclo escolar 2023-2024 y ya hay discusiones sobre los contenidos en los libros de texto gratuitos, los cuales han sido criticados por el Partido Acci\u00f3n Nacional (PAN), cuyo l\u00edder, Marko Cort\u00e9s, ha propuesto destruirlos. Tambi\u00e9n asociaciones de padres han hecho se\u00f1alamientos sobre la poca ense\u00f1anza sobre matem\u00e1ticas, y algunas voces se [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":30812,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[176],"tags":[],"class_list":["post-30811","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/30811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=30811"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/30811\/revisions"}],"predecessor-version":[{"id":30813,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/30811\/revisions\/30813"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/30812"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=30811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=30811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=30811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}