{"id":2919,"date":"2022-02-09T00:53:14","date_gmt":"2022-02-09T00:53:14","guid":{"rendered":"http:\/\/lahora.mx\/?p=2919"},"modified":"2022-02-09T00:53:15","modified_gmt":"2022-02-09T00:53:15","slug":"estudiantes-usan-qr-para-ingresar-en-el-regreso-a-clases-en-buap","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2022\/02\/09\/estudiantes-usan-qr-para-ingresar-en-el-regreso-a-clases-en-buap\/","title":{"rendered":"Estudiantes usan QR para ingresar en el regreso a clases en BUAP"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Los alumnos de las facultades de\u00a0<strong>Ciencias F\u00edsico Matem\u00e1ticas y Ciencias Biol\u00f3gicas,<\/strong>\u00a0as\u00ed como el Instituto de Ciencias de la Benem\u00e9rita Universidad Aut\u00f3noma de Puebla tuvieron que mostrar un c\u00f3digo QR para ingresar a las instalaciones de Ciudad Universitaria, toda vez que este martes iniciaron sus clases presenciales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El protocolo de la universidad estipula<\/strong>&nbsp;que las facultades de la instituci\u00f3n ir\u00e1n entrando de manera gradual, siendo las facultades ya mencionadas las primeras en iniciar clases presenciales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo,\u00a0<strong>las facultades pr\u00f3ximas a abrir sus puertas<\/strong>\u00a0para las clases presenciales ser\u00e1n las de Lenguas, Psicolog\u00eda, Estomatolog\u00eda, lo har\u00e1n el 14 de febrero y el siguiente d\u00eda abrir\u00e1 la facultad de Ingenier\u00eda Qu\u00edmica.<strong><br>Cabe recalcar que durante este mes y parte<\/strong>\u00a0del siguiente ser\u00e1n los regresos graduales en las diversas facultades; de hecho, cada unidad acad\u00e9mica tiene contemplado su propio protocolo para el regreso a las actividades presenciales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los alumnos de las facultades de\u00a0Ciencias F\u00edsico Matem\u00e1ticas y Ciencias Biol\u00f3gicas,\u00a0as\u00ed como el Instituto de Ciencias de la Benem\u00e9rita Universidad Aut\u00f3noma de Puebla tuvieron que mostrar un c\u00f3digo QR para ingresar a las instalaciones de Ciudad Universitaria, toda vez que este martes iniciaron sus clases presenciales. El protocolo de la universidad estipula&nbsp;que las facultades de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":2920,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[175],"tags":[],"class_list":["post-2919","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/2919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2919"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/2919\/revisions"}],"predecessor-version":[{"id":2921,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/2919\/revisions\/2921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/2920"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}