{"id":29185,"date":"2023-07-05T17:17:20","date_gmt":"2023-07-05T17:17:20","guid":{"rendered":"http:\/\/lahora.mx\/?p=29185"},"modified":"2023-07-05T17:17:21","modified_gmt":"2023-07-05T17:17:21","slug":"esto-es-lo-que-gana-el-presiente-del-pais","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2023\/07\/05\/esto-es-lo-que-gana-el-presiente-del-pais\/","title":{"rendered":"Esto es lo que gana el presiente del pa\u00eds"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El presidente Andr\u00e9s Manuel L\u00f3pez Obrador gana 122,257 pesos mensuales libres. \u00c9sa es la informaci\u00f3n oficial disponible a trav\u00e9s de la Plataforma de Transparencia. Y en ese rango salarial se ha mantenido a lo largo de su administraci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo han hecho poniendo en la mira a varios de los organismos aut\u00f3nomos y ahora lo volvieron a hacer, pero con la Suprema Corte de Justicia de la Naci\u00f3n (SCJN). El gobierno federal puso nuevamente sobre la mesa el tema de los salarios de la burocracia y la aplicaci\u00f3n del art\u00edculo 127 de la Constituci\u00f3n, que establece que ning\u00fan funcionario p\u00fablico puede ganar m\u00e1s que el titular del Ejecutivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De hecho, el primer \u201cacto pol\u00edtico\u201d, si se le pudiera llamar as\u00ed, de Luisa Mar\u00eda Alcalde Luj\u00e1n como secretaria de Gobernaci\u00f3n fue precisamente realizar una petici\u00f3n de informaci\u00f3n a la Corte sobre la aplicaci\u00f3n de dicho mandato a nivel interno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cConforme a la atribuci\u00f3n de la @SEGOB_mx de vigilar el cumplimiento de los preceptos constitucionales por las autoridades del pa\u00eds, solicitamos a la @SCJN informe sobre el cumplimiento al art\u00edculo 127 constitucional que proh\u00edbe recibir mayor remuneraci\u00f3n que el Presidente\u201d, comparti\u00f3 la funcionaria el 27 de junio en su cuenta de Twitter.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El tema ha sido recurrente a lo largo de la presente administraci\u00f3n, pues la reducci\u00f3n de los salarios de los funcionarios p\u00fablicos fue una de las promesas de campa\u00f1a de L\u00f3pez Obrador. Pero no lo ha logrado tal como lo ten\u00eda pensado, al menos no del todo. A nivel de su gobierno, se le pas\u00f3 tijera al presupuesto, se recortaron sueldos y se cumpli\u00f3 con el plan. Pero al analizar el resto de la administraci\u00f3n p\u00fablica federal, hay varios cargos que todav\u00eda tienen remuneraciones superiores en el Banco de M\u00e9xico, el INE, la Cofece, el IFT, el Inegi y el Poder Judicial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tal como se ha planteado en este espacio previamente, este tema ha sido objeto de varios rounds entre el gobierno morenista y los \u00f3rganos aut\u00f3nomos, con algunas disposiciones legales que han sido consideradas inconstitucionales por la SCJN, un nuevo intento de reforma pendiente en la C\u00e1mara de Diputados y la presi\u00f3n medi\u00e1tica para que esto se concrete.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La respuesta de la Suprema Corte lleg\u00f3 a Bucareli este lunes, signada por Rafael Coello Cetina, secretario general de Acuerdos de la SCJN. Antes de cualquier cosa, se le explica a la titular de la Segob que ella no tiene facultades para pedirle cuentas a otro de los Poderes de la Uni\u00f3n, s\u00f3lo a las dependencias y entidades del gobierno. Aclarado el punto, se explica que s\u00ed se han implementado medidas de austeridad en los \u00faltimos a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En resumen, en 2018, las y los integrantes de la Corte redujeron en 25% sus remuneraciones. En la actualidad, el salario de las ministras y los ministros es de 206,948 pesos mensuales netos, es decir, casi 70% m\u00e1s que el titular del Ejecutivo. Pero en su explicaci\u00f3n retoman un punto clave, y que incluso fue parte de los argumentos para declarar inconstitucional una parte de la Ley Federal de Remuneraciones, el cual cabe en la siguiente pregunta: \u00bfCu\u00e1nto gana realmente el Presidente?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A decir de la SCJN, la remuneraci\u00f3n del Primer Mandatario no se integra solamente por el sueldo bruto asignado en el Presupuesto de Egresos, y de donde surgen los 122,257 pesos mensuales netos que actualmente gana, sino que incluye tambi\u00e9n \u201ctodas las prestaciones en especie propias del cargo, entre otras, alimentaci\u00f3n, transporte, habitaci\u00f3n, menaje de casa, seguridad, servicios de salud, ente otros\u201d. Y as\u00ed est\u00e1 de hecho considerado en el art\u00edculo 127 de la Constituci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bajo este contexto, de la informaci\u00f3n p\u00fablica disponible se sabe que la partida presupuestal autorizada para este a\u00f1o para las remuneraciones del Presidente es de 2 millones 602,486 pesos (216,874 pesos mensuales). \u00c9sta se divide de la siguiente manera:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sueldos y salarios brutos: 2 millones 88,312 pesos (174,026 pesos mensuales)<br>Seguridad social: 92,460 pesos (7,706 pesos mensuales)<br>Medidas de protecci\u00f3n al salario: 126,996 pesos (10,583 pesos mensuales)<br>Seguros a las personas: 29,236 pesos (2,436 pesos mensuales)<br>Fondos y seguros de ahorro para el retiro: 7,353 pesos (613 pesos mensuales)<br>Prestaciones para condiciones de trabajo y otros: 256,199 pesos (21,350 pesos mensuales)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 recursos p\u00fablicos adicionales son asignados al titular del Ejecutivo? No hay datos concretos que permitan dar respuesta a esta interrogante. En la Plataforma de Transparencia se han hecho m\u00faltiples solicitudes de informaci\u00f3n al respecto \u2013y que son p\u00fablicas\u2013, de ciudadanos que buscan conocer los gastos de vida del Presidente que corren a cargo del erario, incluso sobre los costos que implica que tenga su vivienda en Palacio Nacional. En ninguno de los casos hay una respuesta puntual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSe informa que no se tienen contratos celebrados bajo el rubro de \u2018comidas, vi\u00e1ticos, art\u00edculos de aseo personal, consumibles, entre otros del Presidente de la Rep\u00fablica, Licenciado Andr\u00e9s Manuel L\u00f3pez Obrador\u2019, durante el periodo que refiere el interesado\u2026 En relaci\u00f3n con el resto de la solicitud, no se cuenta con partida de gasto espec\u00edfica para tales efectos, por lo que existe imposibilidad jur\u00eddica y material para informar algo adicional\u201d, es una de las respuestas de la Oficina de la Presidencia a la solicitud con folio 0210000032720. Y as\u00ed hay muchas m\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En respuesta al escrito de la Corte, Luisa Mar\u00eda Alcalde public\u00f3 este martes en su cuenta de Twitter la siguiente declaraci\u00f3n: \u201cLa @SCJN, como m\u00e1ximo Tribunal, deber\u00eda no s\u00f3lo ajustar sus propios salarios sino defender el cumplimiento de la Constituci\u00f3n y garantizar que ning\u00fan funcionario gane m\u00e1s que el Presidente. Es un asunto jur\u00eddico pero, sobre todo, es un asunto moral y de justicia social\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El punto es que sigue sin aclararse cu\u00e1nto gana realmente el Presidente. Una buena respuesta se fundamentar\u00eda en la transparencia, ejercicio que implicar\u00eda reconocer todos los recursos p\u00fablicos que son destinados para sus gastos de vida y determinar as\u00ed el techo real de las remuneraciones de los funcionarios p\u00fablicos para apegarse efectivamente a lo establecido en el art\u00edculo 127 de la Constituci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En aras de la moralidad y la justicia social, tal vez \u00e9ste podr\u00eda ser un buen proyecto para la nueva titular de la Segob, aprovechando que ella misma puso el tema sobre la mesa. Por ahora, de lo poco que es p\u00fablico, lo que s\u00ed sabemos, es que de vales de despensa L\u00f3pez Obrador recibe 1,215 pesos mensuales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Andr\u00e9s Manuel L\u00f3pez Obrador gana 122,257 pesos mensuales libres. \u00c9sa es la informaci\u00f3n oficial disponible a trav\u00e9s de la Plataforma de Transparencia. Y en ese rango salarial se ha mantenido a lo largo de su administraci\u00f3n. Lo han hecho poniendo en la mira a varios de los organismos aut\u00f3nomos y ahora lo volvieron [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":29186,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[3,176],"tags":[],"class_list":["post-29185","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","category-nacional"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/29185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=29185"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/29185\/revisions"}],"predecessor-version":[{"id":29187,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/29185\/revisions\/29187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/29186"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=29185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=29185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=29185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}