{"id":2589,"date":"2022-02-02T00:14:46","date_gmt":"2022-02-02T00:14:46","guid":{"rendered":"http:\/\/lahora.mx\/?p=2589"},"modified":"2022-02-02T00:14:46","modified_gmt":"2022-02-02T00:14:46","slug":"policias-municipales-de-cuautlancingo-que-detuvieron-a-beberly-son-investigados","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2022\/02\/02\/policias-municipales-de-cuautlancingo-que-detuvieron-a-beberly-son-investigados\/","title":{"rendered":"Polic\u00edas municipales de Cuautlancingo que detuvieron a Beberly son investigados"},"content":{"rendered":"<p>Tras la\u00a0<strong>detenci\u00f3n de la joven Beberly Vega el pasado 21 de enero<\/strong>, el\u00a0<strong>\u00c1rea de Asuntos Internos Municipal de Cuautlancingo ha dado inicio a una investigaci\u00f3n en contra de los dos polic\u00edas\u00a0<\/strong>que participaron en el\u00a0<strong>arresto<\/strong>\u00a0de la joven veracruzana.<\/p>\n<p>&nbsp;<\/p>\n<p>En ese sentido, dicha \u00e1rea municipal inici\u00f3 la investigaci\u00f3n luego de que una jueza de control otorgara la\u00a0<strong>libertad a Beberly Vega al no existir las suficientes pruebas sobre las acusaciones que se hicieron en su contra<\/strong>\u00a0por supuesto intento de asalto y ataque directo contra el conductor de Uber de nombre\u00a0<strong>Bende Leyva Romero, de 44 a\u00f1os de edad.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Pues durante\u00a0<strong>la noche del 21 de enero, ingresaron al menos tres reportes del 911 por el delito de violencia de g\u00e9nero contra la joven<\/strong>, sin embargo, los uniformados dieron el informe policial homologado en contra Beberly Vega, acus\u00e1ndola de haber intentado asaltar al conductor de la aplicaci\u00f3n y\u00a0<strong>ocasionarle heridas leves cerca del cuello y en un dedo de la mano derecha.<\/strong><\/p>\n<p>Por tal motivo es que ambos <strong>polic\u00edas, un hombre y una mujer, est\u00e1n siendo investigados<\/strong>.<br \/>\nCabe resaltar que\u00a0<strong>Beberly Vega presentaba una herida en la mano de cuatro cent\u00edmetros y lesiones en las rodillas, marcas y escoriaciones en brazos y en piernas.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras la\u00a0detenci\u00f3n de la joven Beberly Vega el pasado 21 de enero, el\u00a0\u00c1rea de Asuntos Internos Municipal de Cuautlancingo ha dado inicio a una investigaci\u00f3n en contra de los dos polic\u00edas\u00a0que participaron en el\u00a0arresto\u00a0de la joven veracruzana. &nbsp; En ese sentido, dicha \u00e1rea municipal inici\u00f3 la investigaci\u00f3n luego de que una jueza de control otorgara [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":2590,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[175],"tags":[195],"class_list":["post-2589","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-principal"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/2589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2589"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/2589\/revisions"}],"predecessor-version":[{"id":2591,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/2589\/revisions\/2591"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/2590"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2589"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2589"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2589"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}