{"id":23110,"date":"2023-03-14T17:51:58","date_gmt":"2023-03-14T17:51:58","guid":{"rendered":"http:\/\/lahora.mx\/?p=23110"},"modified":"2023-03-14T17:51:58","modified_gmt":"2023-03-14T17:51:58","slug":"lopez-obrador-rechaza-que-haya-persecucion-contra-calderon","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2023\/03\/14\/lopez-obrador-rechaza-que-haya-persecucion-contra-calderon\/","title":{"rendered":"L\u00f3pez Obrador rechaza que haya persecuci\u00f3n contra Calder\u00f3n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El presidente Andr\u00e9s Manuel L\u00f3pez Obrador rechaz\u00f3 que haya una persecuci\u00f3n contra Felipe Calder\u00f3n como el exmandatario acus\u00f3 desde Espa\u00f1a donde particip\u00f3 en un evento en el que se\u00f1al\u00f3 que el caso de Genaro Garc\u00eda Luna, en el cual declar\u00f3 que duda del veredicto y que no se presentaron pruebas, es usado para atacarlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00bfQu\u00e9 persecuci\u00f3n puede haber? Si hubiese persecuci\u00f3n ya hubi\u00e9semos presentado una denuncia en contra del expresidente\u201d, dijo el presidente L\u00f3pez Obrador en su ma\u00f1anera de este martes 14 de marzo y asegur\u00f3 que no est\u00e1 pensando en perseguir a nadie, sino en acabar con la corrupci\u00f3n en M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, critic\u00f3 al exmandatario por defender a su exsecretario de Seguridad, quien fue declarado culpable de los cinco cargos que se imputaban en Estados Unidos, tras se\u00f1alar que ten\u00eda dudas del veredicto, ya que los fiscales no presentaron pruebas y se basaron s\u00f3lo en testimonios de criminales que fueron llevados ante la justicia durante su gobierno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00bfCu\u00e1ndo \u00edbamos a estar viendo de que es juzgado este se\u00f1or Garc\u00eda Luna y sale Felipe Calder\u00f3n a defenderlo?. Es important\u00edsimo, porque lo juzga un tribunal de Estados Unidos y dice Calder\u00f3n \u2018no les creo, no hay pruebas\u2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cOjal\u00e1 pudiese \u00e9l ayudar y explicar qu\u00e9 hac\u00eda Garc\u00eda Luna en su gobierno, por qu\u00e9 consideran de que no hay pruebas y que d\u00e9 una explicaci\u00f3n al pueblo de M\u00e9xico y que adem\u00e1s defendiera abiertamente a Garc\u00eda Luna\u201d, dijo L\u00f3pez Obrador y agreg\u00f3 que incluso Calder\u00f3n podr\u00eda presentar una denuncia contra las autoridades estadounidense que est\u00e1n juzgando al exfuncionario.<br>En sus primeras declaraciones tras el veredicto contra Garc\u00eda Luna, Felipe Calder\u00f3n asegur\u00f3 que era un hombre de leyes y que respetaba la decisiones de los tribunales, \u201csobre todo si se dan conforme a derecho\u201d, aunque reconoci\u00f3 que ten\u00eda sus dudas ya que \u201chubiera esperado ver lo que tanto anunci\u00f3 la fiscal\u00eda: videos, grabaciones, fotograf\u00edas, estados de cuenta, dep\u00f3sitos, y la verdad nada de eso se exhibi\u00f3\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTodo fue con base en testimonios de criminales confesos que, por cierto, a la mayor\u00eda de ellos en nuestro gobierno perseguimos, capturamos y extraditamos\u201d, puntualiz\u00f3 Calder\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras un mes de juicio, Genaro Garc\u00eda Luna fue declarado culpable el 21 de febrero de los cinco cargos en su contra: tres por tr\u00e1fico de coca\u00edna de la mano del c\u00e1rtel de Sinaloa, uno por delincuencia organizada y otro por mentir a las autoridades estadunidenses en su solicitud de naturalizaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Andr\u00e9s Manuel L\u00f3pez Obrador rechaz\u00f3 que haya una persecuci\u00f3n contra Felipe Calder\u00f3n como el exmandatario acus\u00f3 desde Espa\u00f1a donde particip\u00f3 en un evento en el que se\u00f1al\u00f3 que el caso de Genaro Garc\u00eda Luna, en el cual declar\u00f3 que duda del veredicto y que no se presentaron pruebas, es usado para atacarlo. \u201c\u00bfQu\u00e9 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":23111,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[176],"tags":[195],"class_list":["post-23110","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-principal"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/23110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=23110"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/23110\/revisions"}],"predecessor-version":[{"id":23112,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/23110\/revisions\/23112"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/23111"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=23110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=23110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=23110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}