{"id":22509,"date":"2023-03-03T00:35:41","date_gmt":"2023-03-03T00:35:41","guid":{"rendered":"http:\/\/lahora.mx\/?p=22509"},"modified":"2023-03-03T00:35:42","modified_gmt":"2023-03-03T00:35:42","slug":"congreso-de-puebla-aprueba-leyes-secundarias-del-poder-judicial","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2023\/03\/03\/congreso-de-puebla-aprueba-leyes-secundarias-del-poder-judicial\/","title":{"rendered":"Congreso de Puebla aprueba leyes secundarias del Poder Judicial"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Las cuatro leyes secundarias al Poder Judicial, con las que se dar\u00e1 cumplimiento a las reformas promovidas por el exgobernador Miguel Barbosa Huerta, fueron aprobadas por unanimidad en el Congreso de Puebla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En sesi\u00f3n ordinaria y en cuatro votaciones por separado, se dio luz verde a los cuatro ordenamientos que envi\u00f3 el secretario de Gobernaci\u00f3n, Julio Miguel Huerta G\u00f3mez, por acuerdo del gobernador Sergio Salom\u00f3n C\u00e9spedes Peregrina, el pasado 22 de febrero, cuando venci\u00f3 su plazo de expedici\u00f3n.<br>En sus intervenciones, los diputados locales confiaron en que estos cambios garantizar\u00e1n la existencia de contrapesos entre los tres poderes, se profesionalizar\u00e1 la impartici\u00f3n de justicia, se evitar\u00e1 la omisi\u00f3n legislativa y sancionar\u00e1n a los magistrados corruptos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con 34 votos a favor se aprob\u00f3 la Ley Reglamentaria de los Medios de Defensa de la Constituci\u00f3n Pol\u00edtica del Estado Libre y Soberano de Puebla en la que se detallan los medios de control constitucional que pueden ser utilizados por el Poder Judicial para proteger y dar certeza jur\u00eddica sobre el respeto a la Constituci\u00f3n.<br>Tambi\u00e9n delimita el actuar de la Sala Constitucional y recalca la Acci\u00f3n por Omisi\u00f3n Legislativa como mecanismo con el que se resolver\u00e1n las denuncias que se emitan en contra del Congreso de Puebla por no haber legislado o atender reformas en los plazos dictados por las autoridades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs interesante saber que con esta iniciativa va a haber una especie de contrapesos. (\u2026) Hoy se va a regular el tema de la omisi\u00f3n legislativa y quienes pueden, en su caso, recurrir ante la omisi\u00f3n que tengamos, ahora o en el futuro, en este Congreso\u201d, se\u00f1al\u00f3 el diputado panista Eduardo Alc\u00e1ntara.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Ley de Mecanismos Alternativos de Soluci\u00f3n de Controversias del Estado de Puebla, misma que qued\u00f3 aprobada con 34 votos a favor, intentar\u00e1 revertir el atraso que existe en la emisi\u00f3n de sentencias por parte del Tribunal Superior de Justicia (TSJ).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n se crear\u00e1 el Centro de Justicia Alternativa como \u00f3rgano desconcentrado que podr\u00e1 analizar la aplicaci\u00f3n de estos m\u00e9todos en procedimientos penales, civiles, familiares y mercantiles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto, con 34 votos a favor se aprob\u00f3 la Ley Org\u00e1nica de la Defensor\u00eda P\u00fablica del Estado de Puebla, la cual contiene las acciones que garantizar\u00e1n el acceso a la justicia de los poblanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este ordenamiento contempla asuntos del fuero local, en materia penal, familiar, civil, laboral y de justicia c\u00edvica, \u201cmediante la asesor\u00eda, gesti\u00f3n, representaci\u00f3n, patrocinio o defensa de los intereses de las personas que lo soliciten\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Ley de Carrera Judicial del Estado de Puebla se aprob\u00f3 con 35 votos a favor y servir\u00e1 para regular el ingreso, formaci\u00f3n, promoci\u00f3n, evaluaci\u00f3n del desempe\u00f1o, permanencia y separaci\u00f3n de las personas servidoras p\u00fablicas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estos procesos ser\u00e1n vigilados a trav\u00e9s del Consejo de la Judicatura, presidido por Carlos Palafox Galeana, que \u201ccontar\u00e1 con la Escuela Estatal de Formaci\u00f3n Judicial, misma que estar\u00e1 dotada de autonom\u00eda t\u00e9cnica\u201d, con la que se educar\u00e1 y actualizar\u00e1 a los abogados que se desempe\u00f1en como integrantes del Poder Judicial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las cuatro leyes secundarias al Poder Judicial, con las que se dar\u00e1 cumplimiento a las reformas promovidas por el exgobernador Miguel Barbosa Huerta, fueron aprobadas por unanimidad en el Congreso de Puebla. En sesi\u00f3n ordinaria y en cuatro votaciones por separado, se dio luz verde a los cuatro ordenamientos que envi\u00f3 el secretario de Gobernaci\u00f3n, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":22510,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[175],"tags":[227,223],"class_list":["post-22509","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-congreso","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/22509","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=22509"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/22509\/revisions"}],"predecessor-version":[{"id":22511,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/22509\/revisions\/22511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/22510"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=22509"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=22509"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=22509"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}