{"id":21670,"date":"2023-02-16T23:47:38","date_gmt":"2023-02-16T23:47:38","guid":{"rendered":"http:\/\/lahora.mx\/?p=21670"},"modified":"2023-02-16T23:47:39","modified_gmt":"2023-02-16T23:47:39","slug":"profeco-llama-a-a-los-afectados-por-aeromar-sumarse-a-accion-colectiva-para-ser-indemnizado","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2023\/02\/16\/profeco-llama-a-a-los-afectados-por-aeromar-sumarse-a-accion-colectiva-para-ser-indemnizado\/","title":{"rendered":"Profeco llama a a los afectados por Aeromar sumarse a acci\u00f3n colectiva para ser indemnizado"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Aeromar dej\u00f3 de operar definitivamente desde este mi\u00e9rcoles 15 de febrero y con ello al menos 4 mil 900 pasajeros resultaron afectados, ya que cuentan con boletos que no podr\u00e1n usar para viajar debido al cierre de la l\u00ednea a\u00e9rea. Ante ello, la Procuradur\u00eda Federal de Consumidor los llam\u00f3 a sumarse a la acci\u00f3n colectiva que emprendi\u00f3 desde 2019 y en la que el fallo fue favorable, por lo que podr\u00e1n ser indemnizados con el 20 por ciento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El titular de la Profeco, Ricardo Sheffield, pidi\u00f3 que quienes hayan sido afectados por la aerol\u00ednea y a\u00fan no se hayan adherido a esta acci\u00f3n, que lo hagan a trav\u00e9s de la p\u00e1gina o llamando al tel\u00e9fono del consumidor para que presenten la informaci\u00f3n de su boleto y puedan ser incluidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el 25 de abril de 2019 la Profeco hab\u00eda interpuesto una demanda contra Aeromar, la cual gan\u00f3, por lo que la aerol\u00ednea est\u00e1 obligada a reparar los da\u00f1os con el pago de una indemnizaci\u00f3n m\u00e1s el 20% del precio del boleto, as\u00ed como los intereses legales del 9% anual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sheffield aclar\u00f3 que los usuarios podr\u00e1n sumarse a la acci\u00f3n colectivamente independientemente de que acepen las ofertas y descuentos que est\u00e1n ofreciendo Viva Aerobus y Volaris para ganarse a los clientes que dej\u00f3 Aeromar con el cese de sus operaciones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abViva Aerobus y Volaris, que se quieren ganar esos clientes, les est\u00e1n ofreciendo descuentos o vuelos gratis en rutas similares que tambi\u00e9n es algo que pueden aprovechar y que no descarta que de todos modos se adhieran a la acci\u00f3n colectiva contra Aeromar pare recuperar su dinero y la indemnizaci\u00f3n\u201d, indic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Requisitos para sumarse a la acci\u00f3n colectiva contra Aeromar<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los requisitos para poder integrarse a esta acci\u00f3n colectiva de Profeco contra Aeromar, se necesita presentar la siguiente documentaci\u00f3n:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Formato de consentimiento expreso<br>Escrito de relator\u00eda de los hechos firmaron por el consumidor afectado, se\u00f1alando tiempo, modo y lugar de los hechos.<br>Formato adicional de datos personales.<br>Comprobante de compra, ticket o boleto electr\u00f3nico.<br>Los formatos pueden obtenerse a trav\u00e9s del portal de acciones colectivas en la p\u00e1gina https:\/\/acolectivas.profeco.gob.mx\/encuesta.php.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aeromar determin\u00f3 el cese de sus operaciones el 15 de febrero ante los millonarios adeudos que acumula, uno de ellos por m\u00e1s de 522 millones de pesos al Aeropuerto Internacional de la Ciudad de M\u00e9xico, el cual le hab\u00eda dado como plazo para liquidarlo el d\u00eda ante, por lo que ante la falta de pago suspendi\u00f3 el suministro del combustible y de los servicios aeroportuarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La l\u00ednea a\u00e9rea asegur\u00f3 que su decisi\u00f3n se debi\u00f3 a una serie de problemas financieros y a la dificultad de cerrar acuerdos con \u201ccondiciones viables\u201d que permitieran asegurar sus operaciones a largo plazo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl equipo de la compa\u00f1\u00eda realiz\u00f3 profundos ajustes financieros para mejorar su situaci\u00f3n, sin embargo, en un entorno adverso, agravado durante la pandemia del covid-19, las medidas tomadas no fueron suficientes para estabilizar la situaci\u00f3n de la empresa\u201d, afirmo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destinos a los que volaba Aeromar<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aeromar ofrec\u00eda vuelos a 21 destinos nacionales y a 3 internacionales antes de dejar de operar. Lleg\u00f3 al mercado el 7 de noviembre de 1987 con su primer vuelo que despeg\u00f3 desde Toluca y tuvo como destino Acapulco, Guerrero.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vuelos nacionales<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Acapulco<br>Aguascalientes<br>Canc\u00fan<br>Chetumal<br>Ciudad de M\u00e9xico<br>Ciudad Victoria<br>Colima<br>Cozumel<br>Guadalajara<br>Ixtapa Zihuatanejo<br>Ixtepec<br>Mazatl\u00e1n<br>M\u00e9rida<br>Monterrey<br>Piedras Negras<br>Puerto Escondido<br>Puebla<br>Puerto Vallarta<br>Tepic<br>Villahermosa<br>Vuelos internacionales<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Habana<br>Laredo<br>McAllen<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aeromar dej\u00f3 de operar definitivamente desde este mi\u00e9rcoles 15 de febrero y con ello al menos 4 mil 900 pasajeros resultaron afectados, ya que cuentan con boletos que no podr\u00e1n usar para viajar debido al cierre de la l\u00ednea a\u00e9rea. Ante ello, la Procuradur\u00eda Federal de Consumidor los llam\u00f3 a sumarse a la acci\u00f3n colectiva [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":21671,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[176],"tags":[195],"class_list":["post-21670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-principal"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/21670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=21670"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/21670\/revisions"}],"predecessor-version":[{"id":21672,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/21670\/revisions\/21672"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/21671"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=21670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=21670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=21670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}