{"id":21320,"date":"2023-02-12T19:32:12","date_gmt":"2023-02-12T19:32:12","guid":{"rendered":"http:\/\/lahora.mx\/?p=21320"},"modified":"2023-02-12T19:32:13","modified_gmt":"2023-02-12T19:32:13","slug":"ebrard-descarta-tension-con-eu-tras-anuncio-de-amlo","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2023\/02\/12\/ebrard-descarta-tension-con-eu-tras-anuncio-de-amlo\/","title":{"rendered":"Ebrard descarta tensi\u00f3n con EU tras anuncio de AMLO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El canciller Marcelo Ebrard descart\u00f3 este domingo que vaya a exigir alguna tensi\u00f3n con Estados Unidos (EU) luego de que ayer el presidente Andr\u00e9s Manuel L\u00f3pez Obrador anunci\u00f3 que encabezar\u00e1 un movimiento para terminar el bloque econ\u00f3mico que el gobierno estadounidense estableci\u00f3 contra Cuba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En entrevista, tras despedir a Miguel D\u00edaz-Canel, presidente de Cuba, en el Aeropuerto Internacional de Campeche, quien ayer realiz\u00f3 una visita oficia a nuestro pa\u00eds, el titular de Relaciones Exteriores (SRE) afirm\u00f3 que la relaci\u00f3n con EU es muy buena y va a seguir siendo muy buena\u00bb, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El canciller manifest\u00f3 que este anuncio del presidente L\u00f3pez Obrador \u201cno es un af\u00e1n de molestar a Estados Unidos\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo creo porque M\u00e9xico ha guardado esta postura desde 1962, entonces voy a decirlo as\u00ed, M\u00e9xico y Estados Unidos somos aliados, pero no tenemos intereses id\u00e9nticos: M\u00e9xico es un pa\u00eds de Latinoam\u00e9rica, somos un pa\u00eds hispanoparlante y venimos de civilizaciones muy grandes, como la maya. \u00bfQu\u00e9 pensamos? Lo que propone el presidente L\u00f3pez Obrador, ya dejemos atr\u00e1s el pasado, lev\u00e1ntese ese tipo de bloqueos y tratemos de crear una convivencia fraterna en las Am\u00e9ricas, es lo que \u00e9l propone, que nos respetemos todos. Yo creo que en Estados Unidos hay muchas personas que ven con simpat\u00eda esta idea, no creo que el presidente Biden est\u00e9 en contra de esa idea\u00bb, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u00bfLo han llegado a platicar?\u201d, se le pregunt\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cBueno, lo de Cuba no, recientemente pero sabes cu\u00e1l es nuestra postura, yo mismo se le expuse cuando fue la cumbre de las Am\u00e9ricas, y no es un af\u00e1n de molestar a Estados Unidos o tener fricci\u00f3n con Estados Unidos, no es la idea, tienes una mayor\u00eda progresista en Am\u00e9rica Latina: Brasil, Colombia, Bolivia,, M\u00e9xico, Chile, Honduras, Cuba, Venezuela mismo que est\u00e1n ahora en un proceso de negociaci\u00f3n, entonces decimos, el lunes, ma\u00f1ana vamos a iniciar di\u00e1logos, porque as\u00ed lo quiso el gobierno de Colombia y el ELN Para tratar de llegar a un arreglo definitivo, Cuba ha ayudado en eso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cCuba puede ser un factor en favor de que tengamos una estabilidad mejor en Am\u00e9rica Latina que cada pa\u00eds pueda decidir qu\u00e9 hace con su gobierno, porque asumimos que un pa\u00eds le debe decir a otro que hacer, es lo que no coincidimos, yo veo una muy buena relaci\u00f3n con Estados Unidos, no esperar\u00eda que eso cambie y tambi\u00e9n tenemos muy buena relaci\u00f3n con Cuba como la tenemos con les dec\u00eda ayer Brasil, Colombia, Bolivia, Honduras, todos esos pa\u00edses que tienen una ideolog\u00eda en pro, Chile, de la igualdad social, de los derechos, los derechos sociales, pues podemos hacer un di\u00e1logo muy bueno, yo pensar\u00eda que la pol\u00edtica exterior mexicana as\u00ed, la relaci\u00f3n con Estados Unidos. Es una relaci\u00f3n muy buena, pero cada pa\u00eds tiene su propia una idea de las cosas y nos respetamos\u201d, contest\u00f3.<br>Ayer el presidente L\u00f3pez Obrador, frente al presidente cubano Miguel D\u00edaz-Canel, anunci\u00f3 que M\u00e9xico encabezar\u00e1 un grupo de pa\u00edses para lograr el levantamiento del bloqueo econ\u00f3mico que mantiene Estados Unidos desde hace m\u00e1s de 60 a\u00f1os en contra de la isla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El jefe del Ejecutivo federal se comprometi\u00f3 a encabezar un movimiento m\u00e1s activo en defensa de Cuba y \u201cnada de darle trato de pa\u00eds terrorista y ponerlos en la lista negra de supuestos terroristas\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abYo ofrezco al presidente Miguel D\u00edaz-Canel de qu\u00e9 M\u00e9xico va a encabezar un movimiento m\u00e1s activo para que nos unamos todos los pa\u00edses y se defienda la independencia, la soberan\u00eda de Cuba y nada, nada de darle trato de pa\u00eds terrorista ponerlos en la lista negra de supuestos terroristas. Es un pueblo y un gobierno profundamente humano. \u00a1Qu\u00e9 viva el pueblo digno de Cuba!\u00bb, dijo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El canciller Marcelo Ebrard descart\u00f3 este domingo que vaya a exigir alguna tensi\u00f3n con Estados Unidos (EU) luego de que ayer el presidente Andr\u00e9s Manuel L\u00f3pez Obrador anunci\u00f3 que encabezar\u00e1 un movimiento para terminar el bloque econ\u00f3mico que el gobierno estadounidense estableci\u00f3 contra Cuba. En entrevista, tras despedir a Miguel D\u00edaz-Canel, presidente de Cuba, en [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":21321,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[176],"tags":[],"class_list":["post-21320","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/21320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=21320"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/21320\/revisions"}],"predecessor-version":[{"id":21322,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/21320\/revisions\/21322"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/21321"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=21320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=21320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=21320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}