{"id":21284,"date":"2023-02-11T21:56:22","date_gmt":"2023-02-11T21:56:22","guid":{"rendered":"http:\/\/lahora.mx\/?p=21284"},"modified":"2023-02-11T21:56:22","modified_gmt":"2023-02-11T21:56:22","slug":"cinco-camiones-son-consumidos-por-incendio-en-cfe-tehuacan","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2023\/02\/11\/cinco-camiones-son-consumidos-por-incendio-en-cfe-tehuacan\/","title":{"rendered":"Cinco camiones son consumidos por incendio en CFE Tehuac\u00e1n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un incendio en CFE Tehuac\u00e1n consumi\u00f3 cinco camiones tipo pluma, no se reportan personas lesionadas, solo da\u00f1os materiales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El servicio de emergencias fue activado minutos despu\u00e9s de las 19:00 horas de este viernes, fue el cuartel de Bomberos Tehuac\u00e1n quien atendi\u00f3 el llamado, mismos que se dirigieron a la bodega de la Comisi\u00f3n Federal de Electricidad (CFE), de la Divisi\u00f3n Centro Oriente en la Zona Tehuac\u00e1n, ubicada sobre la carretera federal M\u00e9xico-Veracruz, metros antes del Rastro de Aves.<br>Al llegar al sitio, el personal de Bomberos empez\u00f3 a sofocar el fuego, sin embargo el personal era insuficiente para poder mitigarlo por lo que solicitaron el apoyo de otras corporaciones locales y regionales como la Cruz Roja delegaci\u00f3n Tehuac\u00e1n, quienes con su parque vehicular apoyaron en las labores<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue necesaria la presencia de personal de Bomberos de Ajalpan, quienes apoyaron con las labores a trav\u00e9s de una motobomba y una camioneta de primer contacto.<br>Tambi\u00e9n fue desplegada una pipa del Organismos Operador del Servicio de Agua Potable de Tehuac\u00e1n (Oosapat).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unas dos horas m\u00e1s tarde, el incendio logr\u00f3 controlarse, sin registro de lesionados, solo da\u00f1os materiales. Hasta el momento las autoridades desconocen los motivos que originaron el incendio en CFE Tehuac\u00e1n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un incendio en CFE Tehuac\u00e1n consumi\u00f3 cinco camiones tipo pluma, no se reportan personas lesionadas, solo da\u00f1os materiales. El servicio de emergencias fue activado minutos despu\u00e9s de las 19:00 horas de este viernes, fue el cuartel de Bomberos Tehuac\u00e1n quien atendi\u00f3 el llamado, mismos que se dirigieron a la bodega de la Comisi\u00f3n Federal de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":21285,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[175],"tags":[223],"class_list":["post-21284","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/21284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=21284"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/21284\/revisions"}],"predecessor-version":[{"id":21286,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/21284\/revisions\/21286"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/21285"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=21284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=21284"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=21284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}