{"id":20515,"date":"2023-01-31T17:30:05","date_gmt":"2023-01-31T17:30:05","guid":{"rendered":"http:\/\/lahora.mx\/?p=20515"},"modified":"2023-01-31T17:30:06","modified_gmt":"2023-01-31T17:30:06","slug":"mujeres-de-cuetzalan-ganan-premio-nacional","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2023\/01\/31\/mujeres-de-cuetzalan-ganan-premio-nacional\/","title":{"rendered":"Mujeres de Cuetzalan ganan premio nacional"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La organizaci\u00f3n Hueyi Tonal del municipio de Cuetzalan del Progreso obtuvo recientemente el primer lugar a nivel nacional en un concurso que a\u00f1o con a\u00f1o es convocado por el Instituto Nacional Electoral (INE), en colaboraci\u00f3n con el Programa de las Naciones Unidas para el Desarrollo (PNUD), cuyo objetivo es presentar proyectos que propicien la igualdad sustantiva entre hombres y mujeres, as\u00ed como fomenten la participaci\u00f3n pol\u00edtica de las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Leticia Bustos Jim\u00e9nez, vocal de Capacitaci\u00f3n y Educaci\u00f3n C\u00edvica, dijo que dicha actividad es realizada con el fin de que este sector conozca sus derechos, cuya asociaci\u00f3n civil que obtiene el triunfo, recibe facilidades por parte del INE, para el desarrollo de programas de extensi\u00f3n hacia otras mujeres, tal y como se har\u00e1 con esta agrupaci\u00f3n Hueyi Tonal, quien obtuvo el triunfo de este a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan expres\u00f3, estas mujeres se encuentran dedicadas a ofrecer cursos, en torno a la participaci\u00f3n pol\u00edtica de las mujeres, basado en conocimientos, respecto a la organizaci\u00f3n y desarrollo de proyectos que, se encuentren encaminados a mejorar la vida de las mujeres, dentro de las distintas sociedades, especialmente la de las mujeres indignas, quienes tengan la oportunidad de incidir en las actividades propias de su regi\u00f3n, pero sobre todo en el quehacer pol\u00edtico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8216;Le pido permiso a la le\u00f1a y al comal&#8217;: cocineras de humo, de donde nace el verdadero sabor a M\u00e9xico<br>Cabe destacar que por este tipo de proyectos que ejecutan estas organizaciones de la sociedad civil, el INE otorga montos de apoyo que dependen de la modalidad en que participen, cuya tarea es buscar construir un espacio p\u00fablico cada vez m\u00e1s fuerte e igualitario con el impulso de la participaci\u00f3n activa de las mujeres desde distintos \u00e1mbitos y sectores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed mismo, la funcionaria dio a conocer que, para puesta en marcha de dichos proyectos, tambi\u00e9n ha sido de gran val\u00eda la participaci\u00f3n de la gente, con quien se ha logrado una verdadera promoci\u00f3n de los derechos humanos y pol\u00edtico\u2013electorales de las mujeres y actividades de difusi\u00f3n innovadoras, as\u00ed como el desarrollo de agendas y planes de acci\u00f3n que incidan en pol\u00edticas p\u00fablicas de igualdad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mujeres de Cuetzalan representan a Puebla en el Encuentro de Arte Textil Mexicano<br>Por tanto y tras dicho logro, ser\u00e1 ahora tarea de dichas agrupaciones, continuar con su formaci\u00f3n, para apoderarse de espacios p\u00fablicos y la toma de decisiones en condiciones de igualdad, sin discriminaci\u00f3n y sin violencia, siendo la finalidad que, todas las mujeres mexicanas, puedan ejercer sus derechos en materia de libertad, sin violencia y sin discriminaci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La organizaci\u00f3n Hueyi Tonal del municipio de Cuetzalan del Progreso obtuvo recientemente el primer lugar a nivel nacional en un concurso que a\u00f1o con a\u00f1o es convocado por el Instituto Nacional Electoral (INE), en colaboraci\u00f3n con el Programa de las Naciones Unidas para el Desarrollo (PNUD), cuyo objetivo es presentar proyectos que propicien la igualdad [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":20516,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[3,175],"tags":[195,223],"class_list":["post-20515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entretenimiento","category-local","tag-principal","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/20515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=20515"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/20515\/revisions"}],"predecessor-version":[{"id":20517,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/20515\/revisions\/20517"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/20516"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=20515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=20515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=20515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}