{"id":20036,"date":"2023-01-22T20:43:14","date_gmt":"2023-01-22T20:43:14","guid":{"rendered":"http:\/\/lahora.mx\/?p=20036"},"modified":"2023-01-22T20:43:15","modified_gmt":"2023-01-22T20:43:15","slug":"armenta-refuerza-cruzada-de-concientizacion-vs-la-diabetes-la-hipertension-y-la-obesidad","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2023\/01\/22\/armenta-refuerza-cruzada-de-concientizacion-vs-la-diabetes-la-hipertension-y-la-obesidad\/","title":{"rendered":"Armenta refuerza Cruzada de concientizaci\u00f3n vs la diabetes, la hipertensi\u00f3n y la obesidad"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Tochtepec, Puebla. A invitaci\u00f3n de liderazgos de Tochtepec, el senador de Morena por Puebla Alejandro Armenta acudi\u00f3 a ese municipio a presentar su libro \u00abLa Pandemia de Los Edulcorantes en M\u00e9xico\u00bb con la finalidad de fortalecer la campa\u00f1a de concietizaci\u00f3n sobre los h\u00e1bitos alimenticios sanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente de Senado alert\u00f3 sobre los riesgos de consumir excesivamente bebidas azucaradas y productos procesados \u00abque inciden en problemas de obesidad, de hipertensi\u00f3n, y enfermedades cardiovasculares\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El senador poblano ratific\u00f3 que pondera los intereses del pueblo por encima de los intereses particulares \u00bb se trata de privilegiar la libertad de conciencia ante el alto consumo, por ejemplo, de 3 mil 200 vasos de refrescos al a\u00f1o por persona\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El senador Armenta refiri\u00f3 que cada a\u00f1o se incrementa el costo del servicio m\u00e9dico por diabetes e hipertensi\u00f3n, \u00abel costo es de 150 millones de pesos al a\u00f1o para atender las problem\u00e1ticas de salud\u00bb por lo que hizo un llamado a madres y padres de familia a reforzar una alimentaci\u00f3n balanceada en los hogares, por lo que el legislador poblano continuar\u00e1 con estas jornadas de concientizaci\u00f3n en todo el estado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tochtepec, Puebla. A invitaci\u00f3n de liderazgos de Tochtepec, el senador de Morena por Puebla Alejandro Armenta acudi\u00f3 a ese municipio a presentar su libro \u00abLa Pandemia de Los Edulcorantes en M\u00e9xico\u00bb con la finalidad de fortalecer la campa\u00f1a de concietizaci\u00f3n sobre los h\u00e1bitos alimenticios sanos. El presidente de Senado alert\u00f3 sobre los riesgos de consumir [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":20037,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[175],"tags":[223],"class_list":["post-20036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/20036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=20036"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/20036\/revisions"}],"predecessor-version":[{"id":20038,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/20036\/revisions\/20038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/20037"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=20036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=20036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=20036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}