{"id":19911,"date":"2023-01-19T23:14:40","date_gmt":"2023-01-19T23:14:40","guid":{"rendered":"http:\/\/lahora.mx\/?p=19911"},"modified":"2023-01-19T23:14:41","modified_gmt":"2023-01-19T23:14:41","slug":"proponen-en-el-congreso-del-estado-aumentar-sanciones-a-quien-conduzca-en-estado-de-ebriedad","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2023\/01\/19\/proponen-en-el-congreso-del-estado-aumentar-sanciones-a-quien-conduzca-en-estado-de-ebriedad\/","title":{"rendered":"Proponen en el Congreso del Estado aumentar sanciones a quien conduzca en estado de ebriedad"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En Sesi\u00f3n Ordinaria de la LXI Legislatura del Congreso del Estado se dio lectura a una propuesta de reforma al art\u00edculo 85 del C\u00f3digo Penal del Estado para incrementar las penas cuando se cometa un delito al conducir un veh\u00edculo en estado de ebriedad o bajo el influjo de estupefacientes, enervantes, psicotr\u00f3picos o cualquier otra sustancia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La iniciativa fue presentada por la diputada Aurora Sierra Rodr\u00edguez quien explic\u00f3 que la propuesta es incrementar de tres d\u00edas a cinco a\u00f1os de presi\u00f3n y multa de 100 a 150 Unidades de Medida y Actualizaci\u00f3n cuando se cometa el delito al conducir veh\u00edculo de motor en estado de ebriedad o bajo el influjo de estupefacientes, enervantes, psicotr\u00f3picos o cualquier otra sustancia que produzca un efecto similar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El dictamen se turn\u00f3 a la Comisi\u00f3n de Procuraci\u00f3n y Administraci\u00f3n de Justicia para su resoluci\u00f3n procedente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En otro momento de la sesi\u00f3n el diputado Roberto Bautista Lozano rindi\u00f3 protesta como diputado suplente del distrito 13 con cabecera en Tepeaca ante el Pleno de la LXI Legislatura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como parte de la Sesi\u00f3n, se dio lectura a la memoria que present\u00f3 la Comisi\u00f3n Permanente sobre el uso de sus atribuciones durante su ejercicio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al hacer uso de la palabra, en la Sesi\u00f3n, la diputada Nora Merino Escamilla present\u00f3 un Punto de Acuerdo para exhortar al presidente municipal de Puebla para que informe al Poder Legislativo el monto exacto y su divisi\u00f3n por ramo o materia, de subejercicio de su administraci\u00f3n del a\u00f1o fiscal 2022 y si est\u00e1 a tiempo de reprogramar el recurso para el funcionamiento de las juntas auxiliares.<br>El dictamen se turn\u00f3 a la Comisi\u00f3n de Control, Vigilancia y Evaluaci\u00f3n de la Auditor\u00eda Superior del Estado para su an\u00e1lisis y resoluci\u00f3n procedente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La diputada Guadalupe Leal Rodr\u00edguez present\u00f3 un Punto de Acuerdo para exhortar al Ayuntamiento de Puebla a dar mantenimiento al Mercado Amalucan incluyendo la prestaci\u00f3n de los servicios necesarios para la sana convivencia y la libre concurrencia para el desarrollo de la actividad comercial y beneficio de la ciudadan\u00eda en general.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EL dictamen se turn\u00f3 a la Comisi\u00f3n de Asuntos Municipales para su an\u00e1lisis y resoluci\u00f3n procedente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">TURNA MESA DIRECTIVA DIVERSAS INICIATIVAS Y PUNTOS DE ACUERDO<br>En otro momento del orden del d\u00eda, la Mesa Directiva dio cuenta del paquete de iniciativas que, por separado, present\u00f3 la diputada Karla Mart\u00ednez Gallegos, para modificar la Constituci\u00f3n, la Ley de la Comisi\u00f3n de Derechos Humanos, el C\u00f3digo de Procedimientos Civiles, la Ley de V\u00edctimas y la Ley del Servicio de la Defensor\u00eda P\u00fablica, con el objetivo de garantizar que en los procedimientos las y los integrantes de los pueblos y comunidades ind\u00edgenas cuenten con la asistencia de un int\u00e9rprete profesional o pr\u00e1ctico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las iniciativas fueron turnadas a la Comisi\u00f3n de Gobernaci\u00f3n y Puntos Constitucionales, la de Derechos Humanos y la de Procuraci\u00f3n y Administraci\u00f3n de Justicia, respectivamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n dio cuenta de la iniciativa de decreto que present\u00f3 la diputada Nancy Jim\u00e9nez Morales present\u00f3 una iniciativa de reforma a la Ley para el Acceso de las Mujeres a Una Vida Libre de Violencia, con el fin de homologar la definici\u00f3n de violencia feminicida con lo expuesto en la Ley General.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EL dictamen se turn\u00f3 a la Comisi\u00f3n de Igualdad de G\u00e9nero para su an\u00e1lisis y resoluci\u00f3n procedente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, se dio cuenta de la iniciativa de la diputada Karla Rodr\u00edguez Palacios quien propuso reformas la Ley para Prevenir y Eliminar la Discriminaci\u00f3n del Estado para considerar como discriminaci\u00f3n que se solicite constancia de antecedentes no penales para el acceso o permanencia a un cargo p\u00fablico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">EL dictamen se turn\u00f3 a la Comisi\u00f3n de Derechos Humanos para su an\u00e1lisis y resoluci\u00f3n correspondiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n la Mesa Directiva dio cuenta de la iniciativa que propuso la diputada M\u00f3nica Rodr\u00edguez Della Vecchia para considerar que el gobierno estatal cuente con un sistema educativo que tenga como fin la formaci\u00f3n en el respeto de los derechos humanos e igualdad entre mujeres y hombres y respeto a la dignidad humana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La iniciativa de decreto fue turnada a la Comisi\u00f3n de Igualdad de G\u00e9nero para su an\u00e1lisis y resoluci\u00f3n correspondiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Mesa Directiva dio cuenta del Punto de Acuerdo que present\u00f3 la diputada Daniela Mier Ba\u00f1uelos por el que pide exhortar a la Secretar\u00eda de Cultura que inspeccione museos, teatros y dem\u00e1s inmuebles de la dependencia para realizar las gestiones necesarias para el mantenimiento de estos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Punto de Acuerdo fue turnado a la Comisi\u00f3n de Cultura para su an\u00e1lisis correspondiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Mesa Directiva dio cuenta del Punto de Acuerdo del diputado Iv\u00e1n Herrera Villag\u00f3mez quien propuso exhortar a la Junta Gobierno del Instituto Nacional de Estad\u00edstica y Geograf\u00eda para que en el pr\u00f3ximo Censo de poblaci\u00f3n y posteriores, en la encuesta nacional, se considere el conteo de la poblaci\u00f3n perteneciente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Punto de Acuerdo fue turnado a la Comisi\u00f3n de Grupos Vulnerables para su an\u00e1lisis correspondiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Mesa Directiva dio cuenta del Punto de Acuerdo del diputado Adolfo Alatriste Cant\u00fa quien propuso exhortar al titular de la Secretar\u00eda de Seguridad P\u00fablica para que coadyuve con los ayuntamientos del Distrito 26 para que realicen las funciones de prevenci\u00f3n, incluyendo la investigaci\u00f3n para hacerla efectiva, y de reacci\u00f3n dirigidas a salvaguardar la integridad y patrimonio de las personas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Punto de Acuerdo fue turnado a la Comisi\u00f3n de Seguridad P\u00fablica para su an\u00e1lisis correspondiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En Asuntos Generales el diputado Fernando Morales Mart\u00ednez present\u00f3 un Punto de Acuerdo con el objetivo de que los recursos destinados a salud los maneje el Gobierno del Estado, esto, ante las nuevas disposiciones del Gobierno Federal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Punto de Acuerdo fue turnado a la Comisi\u00f3n de Salud para su an\u00e1lisis y resoluci\u00f3n correspondiente.<br>Por su parte la diputada Ruth Z\u00e1rate Dom\u00ednguez propuso un Punto de Acuerdo para hacer que se realicen las supervisiones necesarias en el relleno sanitario de los municipios que involucran a los municipios de Quecholac, Felipe \u00c1ngeles y Felipe Bravo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Punto de Acuerdo fue turnado a la Comisi\u00f3n de Medio Ambiente, Recursos Naturales y Cambio Clim\u00e1tico para su an\u00e1lisis y resoluci\u00f3n correspondiente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En Sesi\u00f3n Ordinaria de la LXI Legislatura del Congreso del Estado se dio lectura a una propuesta de reforma al art\u00edculo 85 del C\u00f3digo Penal del Estado para incrementar las penas cuando se cometa un delito al conducir un veh\u00edculo en estado de ebriedad o bajo el influjo de estupefacientes, enervantes, psicotr\u00f3picos o cualquier otra [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":19912,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[175],"tags":[227],"class_list":["post-19911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-congreso"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/19911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=19911"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/19911\/revisions"}],"predecessor-version":[{"id":19913,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/19911\/revisions\/19913"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/19912"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=19911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=19911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=19911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}