{"id":18298,"date":"2022-12-19T13:49:03","date_gmt":"2022-12-19T13:49:03","guid":{"rendered":"http:\/\/lahora.mx\/?p=18298"},"modified":"2022-12-19T13:49:04","modified_gmt":"2022-12-19T13:49:04","slug":"atencion-bimbo-incrementa-sus-precios-a-partir-de-este-lunes","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2022\/12\/19\/atencion-bimbo-incrementa-sus-precios-a-partir-de-este-lunes\/","title":{"rendered":"!Atenci\u00f3n\u00a1 Bimbo incrementa sus precios a partir de este lunes"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La empresa inform\u00f3 en su reporte al tercer trimestre del a\u00f1o que continuar\u00edan los incrementos en el precio final a sus clientes en el primer trimestre del 2023, despu\u00e9s de tres ajustes que ha hecho a lo largo del presente a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como una respuesta al incremento en el costo de los insumos de sus productos, Bimbo incrementar\u00e1 este lunes 19 de diciembre el precio de sus productos. La empresa inform\u00f3 en su reporte al tercer trimestre del a\u00f1o que continuar\u00edan los incrementos en el precio final a sus clientes en el primer trimestre del 2023, despu\u00e9s de tres ajustes que ha hecho a lo largo del presente a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La empresa cotizada en Bolsa, incrementar\u00e1 este lunes el \u00faltimo incremento en sus productos al consumidor final, de acuerdo con la Alianza Nacional de Peque\u00f1os Comerciantes (Anpec).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre los productos que aumentaron sus precios, entre uno y cuatro pesos, est\u00e1 el pan blanco grande a 45 pesos desde los 42 pesos, el pan blanco chico ahora cuesta 36 pesos, antes 32 pesos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destaca el incremento en estos productos porque fueron los que se integraron dentro del Paquete contra la Inflaci\u00f3n y la Carest\u00eda (Pacic), promovido por el gobierno federal para controlar el alza de precios de la canasta b\u00e1sica de M\u00e9xico por la inflaci\u00f3n. Este acuerdo durar\u00eda seis meses, por lo que este lapso ya pas\u00f3 y Bimbo procedi\u00f3 a incluir estos b\u00e1sicos entre los sus ajustes de precios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otros productos que subir\u00e1n ser\u00e1 el precio de las donas azucaradas, un peso, el pan tostado pasar\u00e1 de 31 a 32 pesos en territorio mexicano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLas empresas de productos de consumo, ya sean alimentarias o no alimentarias, se han enfrentado y contin\u00faan enfrentando como nosotros, cantidades incre\u00edbles de inflaci\u00f3n. Dados los vientos en contra que enfrentamos, particularmente en el cuarto y primer trimestre de 2023 vamos a hacer lo que tenemos que hacer en relaci\u00f3n con los precios. Es dif\u00edcil, pero hay que hacerlo\u201d, dijo en su reciente conferencia con analistas, el presidente de Bimbo Bakeries Estados Unidos, Alfred Penny.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Marisol Huerta, analista en Grupo Financiero Ve por M\u00e1s (Bx+) explic\u00f3 que los resultados de Grupo Bimbo han sido positivos porque est\u00e1n compensando sus vol\u00famenes con el aumento de precios de sus productos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las ventas netas del grupo panificador ascendieron a 102,821 millones de pesos en el tercer trimestre de este a\u00f1o, un aumento de 20% en comparaci\u00f3n con igual lapso del 2021, principalmente por la mezcla de precios favorable y el incremento de los vol\u00famenes, dijo la panificadora mexicana en su tercer reporte financiero del a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La especialista de Bx+ record\u00f3 que el aumento en productos de Bimbo se ha hecho principalmente en las categor\u00edas de pan dulce, pastelitos, galletas y botanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo que esperar\u00edamos para el pr\u00f3ximo a\u00f1o es que la empresa obtenga mejores coberturas y menos presiones porque hay un entorno de materias primas (ma\u00edz y trigo) un poco m\u00e1s estable\u201d, consider\u00f3 Marisol Huerta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Record\u00f3 que Bimbo tradicionalmente suben el precio de sus productos por lo menos una vez al a\u00f1o, ya sea a principios o finales del periodo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El director asociado de Investigaci\u00f3n Burs\u00e1til en Actinver Casa de Bolsa, Valent\u00edn Mendoza, explic\u00f3 que Bimbo ha aplicado medidas de aumento de precios cuidado el balance para no afectar su rentabilidad y la demanda de sus productos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEs normal esperar que las empresas aumenten los precios en un entorno con inflaci\u00f3n y con materias primas encareci\u00e9ndose, sobre todo porque este a\u00f1o ha sido at\u00edpico y las empresas han tenido que hacer el traspaso de precios sin afectar la demanda y ver qu\u00e9 tanto puede afectar al consumidor, por eso hemos visto los aumentos paulatinos en los productos de Bimbo, pero no ha sido a \u00fanica empresa que ha tomado esta medida\u00bb, resalt\u00f3 Mendoza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLa gran pregunta sigue siendo hasta cu\u00e1ndo vamos a ver un punto de inflexi\u00f3n para que el consumidor empiece a disminuir sus vol\u00famenes de consumo porque considera que los precios de los productos ya son elevados, aunque es complicado que la gente pueda dejar de consumir pan es posible ver un efecto sustituto entre otro alimento similar o marcas, etc.\u00bb, a\u00f1adi\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A pesar de las presiones inflacionarias de a\u00f1o, reflejadas en el incremento de sus costos en materias primas (como el trigo y la energ\u00eda), fletes y mano de obra, el desempe\u00f1o en Bolsa ha sido positivo para la ic\u00f3nica empresa del \u201cOsito Bimbo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La panificadora Grupo Bimbo se ubica entre las cinco firmas ganadoras de la Bolsa Mexicana de Valores (BMV), en un a\u00f1o vol\u00e1til y de ca\u00eddas para los mercados burs\u00e1tiles mundiales, con un rendimiento acumulado de 35.92% en 2022.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Otras empresas con mayores ganancias son la minorista Chedraui (+99.10%); las financieras Banco del Baj\u00edo (+63.90%); Gentera (+63.30%); y Grupo Financiero Inbursa (+40.30%).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Analistas explican que la empresa ha presentado n\u00fameros positivos, no solo en su cotizaci\u00f3n en el mercado accionario, sino en ventas que han marcado r\u00e9cord trimestre a trimestre en este a\u00f1o, apoyado por las diversas estrategias para compensar el aumento de la inflaci\u00f3n, como el aumento de precios de sus productos, la combinaci\u00f3n de categor\u00edas y productos, as\u00ed como iniciativas para aumentar su productividad<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La empresa inform\u00f3 en su reporte al tercer trimestre del a\u00f1o que continuar\u00edan los incrementos en el precio final a sus clientes en el primer trimestre del 2023, despu\u00e9s de tres ajustes que ha hecho a lo largo del presente a\u00f1o. Como una respuesta al incremento en el costo de los insumos de sus productos, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":18299,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[176],"tags":[195],"class_list":["post-18298","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-principal"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/18298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=18298"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/18298\/revisions"}],"predecessor-version":[{"id":18300,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/18298\/revisions\/18300"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/18299"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=18298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=18298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=18298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}