{"id":16356,"date":"2022-11-14T04:02:53","date_gmt":"2022-11-14T04:02:53","guid":{"rendered":"http:\/\/lahora.mx\/?p=16356"},"modified":"2022-11-14T04:02:54","modified_gmt":"2022-11-14T04:02:54","slug":"opositores-a-la-4t-enganan-al-pueblo-el-ine-no-va-a-desaparecer-sergio-salomon","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2022\/11\/14\/opositores-a-la-4t-enganan-al-pueblo-el-ine-no-va-a-desaparecer-sergio-salomon\/","title":{"rendered":"Opositores a la 4T enga\u00f1an al pueblo, el INE no va a desaparecer: Sergio Salom\u00f3n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Durante las asambleas informativas con militantes y simpatizantes de Morena, el diputado local, Sergio Salom\u00f3n C\u00e9spedes Peregrina se\u00f1al\u00f3 que los opositores a la 4T enga\u00f1an al pueblo cuando dicen que el Instituto Nacional Electoral (INE) va a desaparecer, pues lo que propone la Reforma Electoral es una transformaci\u00f3n que fortalezca la democracia y genere ahorros para destinar mayores recursos en \u00e1reas prioritarias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente de la Junta de Gobierno y Coordinaci\u00f3n Pol\u00edtica del Congreso del Estado asegur\u00f3 que los gobiernos de la Cuarta Transformaci\u00f3n se conducen con verdades y compromisos, pero hay un grupo de personas con intereses particulares que pretenden enga\u00f1ar al pueblo con expresiones contrarias a lo que se propone con la Reforma Electoral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sergio Salom\u00f3n C\u00e9spedes Peregrina destac\u00f3 los principales puntos de la Reforma Electoral, como ahorros por 50 mil millones de pesos; eliminar las prerrogativas ordinarias de los partidos \u2013recursos a los que acceden todo el a\u00f1o\u2014 y que s\u00f3lo cuenten con estos subsidios en campa\u00f1as; reducir de 11 a siete consejeros en el INE; disminuir la cantidad de diputados federales; generar condiciones para emitir un voto electr\u00f3nico; y elegir a las autoridades electorales con un voto directo de los ciudadanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aclar\u00f3 que esta es apenas una propuesta del presidente Andr\u00e9s Manuel L\u00f3pez Obrador, que se analizar\u00e1 en el Congreso de la Uni\u00f3n; para aprobarla se requerir\u00e1 del consenso de las fuerzas pol\u00edticas y de un an\u00e1lisis a profundidad, pero el principal objetivo es transformar al INE.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por lo anterior, pidi\u00f3 a los militantes y simpatizantes de Morena mantenerse unidos en torno al presidente Andr\u00e9s Manuel L\u00f3pez Obrador y tambi\u00e9n al gobernador Miguel Barbosa Huerta, para continuar con la transformaci\u00f3n a trav\u00e9s de la Reforma Electoral, pero tambi\u00e9n de todo el r\u00e9gimen, con el objetivo de acabar con la corrupci\u00f3n, la impunidad y la desigualdad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El diputado local particip\u00f3 en las asambleas informativas que se realizaron en Iz\u00facar de Matamoros, Atlixco, Ajalpan y Tehuac\u00e1n, donde las y los presentes refrendaron su apoyo a Claudia Sheinbaum para continuar con la transformaci\u00f3n iniciada por el presidente de la Rep\u00fablica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante las asambleas informativas con militantes y simpatizantes de Morena, el diputado local, Sergio Salom\u00f3n C\u00e9spedes Peregrina se\u00f1al\u00f3 que los opositores a la 4T enga\u00f1an al pueblo cuando dicen que el Instituto Nacional Electoral (INE) va a desaparecer, pues lo que propone la Reforma Electoral es una transformaci\u00f3n que fortalezca la democracia y genere ahorros [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":16357,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[175],"tags":[223],"class_list":["post-16356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/16356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=16356"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/16356\/revisions"}],"predecessor-version":[{"id":16358,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/16356\/revisions\/16358"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/16357"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=16356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=16356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=16356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}