{"id":14417,"date":"2022-10-04T17:04:06","date_gmt":"2022-10-04T17:04:06","guid":{"rendered":"http:\/\/lahora.mx\/?p=14417"},"modified":"2022-10-04T17:04:07","modified_gmt":"2022-10-04T17:04:07","slug":"privada-de-la-vida-buscando-a-su-hija-en-villa-frontera-en-puebla","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2022\/10\/04\/privada-de-la-vida-buscando-a-su-hija-en-villa-frontera-en-puebla\/","title":{"rendered":"Privada de la vida buscando a su hija en Villa Frontera, en Puebla"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La mujer rafagueada y asesinada en Villa Frontera, en Puebla, la madrugada de hoy martes 04 de octubre, era Blanca Esmeralda Gallardo, una \u201cmadre buscadora\u201d que denunci\u00f3 la desaparici\u00f3n de su hija, Betzab\u00e9 Alvarado, la cual fue vista por \u00faltima vez el 13 de enero de 2021 y cuyo presunto responsable ser\u00eda un narcomenudista, hoy tambi\u00e9n sospechoso del asesinato de la mam\u00e1 de la v\u00edctima de desaparici\u00f3n forzada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tras el asesinato de la mujer de alrededor de 45 a\u00f1os de edad, y con el avance de las indagatorias, se supo que se trataba de Blanca Esmeralda, al parecer originaria de Veracruz, pero radicaba en Puebla desde ya hace algunos a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s de la desaparici\u00f3n de su hija Betzab\u00e9 Alvarado Gallardo, de 22 a\u00f1os de edad, en diversas ocasiones expres\u00f3 sus sospechas de que la joven podr\u00eda haber sido v\u00edctima de trata de personas e incluso responsabiliz\u00f3 recientemente a un narcomenudista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La se\u00f1ora Blanca Esmeralda, quien todav\u00eda el pasado 9 de mayo concedi\u00f3 una entrevista a e-consulta, refiri\u00f3 que su hija desapareci\u00f3 junto con una amiga en Villa Frontera y diez despu\u00e9s de la desaparici\u00f3n, la pareja sentimental de Betza, como la llaman de cari\u00f1o, le quit\u00f3 a su nieta y le prohibi\u00f3 verla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por si fuera poco, adem\u00e1s de enfrentarse a estas dos situaciones, la se\u00f1ora Blanca, meses atr\u00e1s perdi\u00f3 a su esposo quien se contagi\u00f3 de covid-19 y muri\u00f3, as\u00ed que solo quedaban ella y su hijo Enrique, de 12 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dispuesta a dedicarse solo a la b\u00fasqueda de su hija, envi\u00f3 al menor con familiares fuera del estado, pero \u00e9l no quiso dejarla sola y se convirti\u00f3 en su motor para salir adelante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Betzab\u00e9 fue vista por \u00faltima vez en una motocicleta que era de su propiedad. Junto a su vecina y amiga, Fabiola Narv\u00e1ez Rojas, sali\u00f3 rumbo a la Central de Abasto y desaparecieron junto con la motocicleta en que viajaban.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El hombre que, al parecer, se llev\u00f3 a su hija y a Fabiola, fue asesinado en los l\u00edmites de Puebla y San Pablo del Monte. La pareja sentimental de este sujeto fue baleada a la puerta de su casa, ubicada tambi\u00e9n en Villa Frontera, y al salir del hospital la detuvieron por la desaparici\u00f3n de ambas j\u00f3venes, pero no quiso hablar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Blanca todav\u00eda en vida mencion\u00f3 que su hija pudo haber sido v\u00edctima de trata de personas y en su desesperaci\u00f3n ingres\u00f3 a Tenancingo, Tlaxcala, tierra de nadie y para\u00edso de la explotaci\u00f3n sexual. Ah\u00ed, un hombre le apunt\u00f3 con una pistola en la cabeza; tir\u00f3 a la basura la ficha de desaparici\u00f3n de Betza y le pidi\u00f3 que se retirara de inmediato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque lleg\u00f3 una patrulla, los oficiales solo la encaminaron para asegurarse que saliera del municipio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En medio de su desesperaci\u00f3n, Blanca acudi\u00f3 a diversos bares localizados en zonas con alto \u00edndice delictivo, como el mercado de la Uni\u00f3n, o donde escuchaba que hab\u00eda \u201cmuchachas nuevas\u201d, lo anterior lo hac\u00eda con la esperanza de encontrar a su hija.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, tras las recientes denuncias que esta madre buscadora, Blanca Esmeralda Gallardo, hizo contra un narcomenudista, hoy 4 de octubre fue asesinada en Villa Frontera, en Puebla, de siete impactos de bala; ante la dimensi\u00f3n de los hechos se espera que pronto la Fiscal\u00eda General del Estado (FGE) se pronuncie sobre el caso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La mujer rafagueada y asesinada en Villa Frontera, en Puebla, la madrugada de hoy martes 04 de octubre, era Blanca Esmeralda Gallardo, una \u201cmadre buscadora\u201d que denunci\u00f3 la desaparici\u00f3n de su hija, Betzab\u00e9 Alvarado, la cual fue vista por \u00faltima vez el 13 de enero de 2021 y cuyo presunto responsable ser\u00eda un narcomenudista, hoy [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":14418,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[175,226],"tags":[195,223],"class_list":["post-14417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","category-policia","tag-principal","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/14417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=14417"}],"version-history":[{"count":2,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/14417\/revisions"}],"predecessor-version":[{"id":14928,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/14417\/revisions\/14928"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/14418"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=14417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=14417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=14417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}