{"id":14336,"date":"2022-10-03T12:40:01","date_gmt":"2022-10-03T12:40:01","guid":{"rendered":"http:\/\/lahora.mx\/?p=14336"},"modified":"2022-10-03T12:40:01","modified_gmt":"2022-10-03T12:40:01","slug":"durante-este-sexenio-se-llevaron-acabo-3-casos-de-espionaje-con-version-mejorada-de-software-pegasus","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2022\/10\/03\/durante-este-sexenio-se-llevaron-acabo-3-casos-de-espionaje-con-version-mejorada-de-software-pegasus\/","title":{"rendered":"Durante este sexenio se llevaron  acabo 3 casos de espionaje con versi\u00f3n mejorada de software Pegasus"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Al menos tres periodistas y defensores de derechos humanos denunciaron haber sido espiados con una versi\u00f3n mejorada del software esp\u00eda \u00abPegasus\u00bb, que se utiliz\u00f3 en el sexenio de Enrique Pe\u00f1a Nieto y del que no se conoc\u00eda su uso en la actual administraci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una investigaci\u00f3n conjunta de medios y colectivos como el Citizen Lab en Toronto confirmaron la vulneraci\u00f3n en datos personales y en celulares del periodista Ricardo Raphael, el defensor de Derechos Humanos en Nuevo Laredo, Raymundo Ramos y un reportero no identificado por nombre del portal Animal Pol\u00edtico.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan Animal Pol\u00edtico y Proceso, el espionaje se realiz\u00f3 con una versi\u00f3n m\u00e1s agresiva de Pegasus, donde la v\u00edctima recibe una liga con el llamado \u00abmalware\u00bb y ya no es necesario que siquiera d\u00e9 click para que est\u00e9 infectado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con el colectivo que publica las denuncias, la compa\u00f1\u00eda israel\u00ed NSO, propietaria de Pegasus, s\u00f3lo vende este servicio a gobiernos, y tras la filtraci\u00f3n masiva de documentos de la Secretar\u00eda de la Defensa Nacional la semana pasada, fue posible ligar a la Sedena a trav\u00e9s de contratos con compa\u00f1\u00edas autorizadas a comercializar el Pegasus en M\u00e9xico.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su nota sobre el tema, Animal Pol\u00edtico recuerda que entre 2016 y 2017, dentro del sexenio de Enrique Pe\u00f1a Nieto, la Sedena, el Centro de Investigaci\u00f3n y Seguridad Nacional (Cisen), adem\u00e1s de la Agencia de Investigaci\u00f3n Criminal utilizaron Pegasus para espiar a activistas y defensores de derechos humanos, seg\u00fan se hizo p\u00fablico por diversas investigaciones; a la fecha, la denuncia y posterior investigaci\u00f3n no ha avanzado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y en su nota sobre el tema, el semanario Proceso recuerda que dos semanas despu\u00e9s de su toma de protesta, el presidente Andr\u00e9s Manuel L\u00f3pez Obrador hab\u00eda asegurado que su equipo no realizar\u00eda espionaje ilegal con este u otro spyware, y declar\u00f3 que \u00abya pueden ustedes hablar tranquilamente por tel\u00e9fono\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, en agosto de 2021 neg\u00f3 cualquier v\u00ednculo con empresas de tecnolog\u00eda que vendieran este tipo de software, tales como NSO, creadora de Pegasus, y en enero de este a\u00f1o, el mandatario reiter\u00f3 que no se realizaba espionaje; dijo que \u00abya no existe el estado mayor presidencial, ya eso ya cambi\u00f3\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Animal Pol\u00edtico y Ricardo Raphael, v\u00edctimas de Pegasus<br>La investigaci\u00f3n relaciona las fechas del hackeo a Raphael con la redacci\u00f3n de su libro \u00abHijo de la Guerra\u00bb, basada en entrevistas sobre el grupo de narcotr\u00e1fico Los Zetas, en tanto que el ataque al reportero de Animal Pol\u00edtico se extiende a todo el portal, seg\u00fan su director Daniel Moreno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSolo revisando el caso de este periodista, puedo decir que \u00fanicamente en Whatsapp estaba en m\u00e1s de 25 chats donde est\u00e1 todo el staff de Animal Pol\u00edtico. En este caso no es solamente el espionaje a un reportero, sino a todo el personal Animal Pol\u00edtico; ellos tuvieron acceso a toda la informaci\u00f3n de todo lo que est\u00e1bamos haciendo durante un a\u00f1o\u201d, declara Moreno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La tercera de las v\u00edctimas es Raymundo Ramos, a quien atacaron el 28 de agosto, el 2 y el 3 de septiembre. Animal Pol\u00edtico apunta que \u00abApenas cuatro d\u00edas antes del primer ataque, el peri\u00f3dico El Universal revel\u00f3 que, tras un enfrentamiento con presuntos integrantes del crimen organizado el 3 de julio de 2020, militares ordenaron matar a un sobreviviente, y puso en evidencia que en el actual gobierno las Fuerzas Armadas continuaban cometiendo violaciones a derechos humanos, pese al discurso contrario del presidente L\u00f3pez Obrador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEl Comit\u00e9 Estatal de Derechos Humanos de Nuevo Laredo (CEDHNL) continu\u00f3 documentando ese caso a ra\u00edz de las quejas interpuestas en contra de los militares por parte de familiares de los civiles asesinados, quienes se presume eran v\u00edctimas de secuestro. Por ello es que Ramos particip\u00f3 en las denuncias p\u00fablicas en medios de comunicaci\u00f3n y tuvo reuniones con funcionarios de la Secretar\u00eda de Gobernaci\u00f3n, en la Oficina del Alto Comisionado de la ONU\u00bb, apunta Animal.<br>Suscr\u00edbete aqu\u00ed para recibir directo en tu correo nuestras newsletters sobre noticias del d\u00eda, opini\u00f3n, planes para el fin de semana, Qatar 2022 y muchas opciones m\u00e1s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al menos tres periodistas y defensores de derechos humanos denunciaron haber sido espiados con una versi\u00f3n mejorada del software esp\u00eda \u00abPegasus\u00bb, que se utiliz\u00f3 en el sexenio de Enrique Pe\u00f1a Nieto y del que no se conoc\u00eda su uso en la actual administraci\u00f3n. Una investigaci\u00f3n conjunta de medios y colectivos como el Citizen Lab en [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":14338,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[176],"tags":[195],"class_list":["post-14336","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-principal"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/14336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=14336"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/14336\/revisions"}],"predecessor-version":[{"id":14339,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/14336\/revisions\/14339"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/14338"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=14336"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=14336"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=14336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}