{"id":1184,"date":"2022-01-04T17:30:55","date_gmt":"2022-01-04T17:30:55","guid":{"rendered":"http:\/\/lahora.mx\/?p=1184"},"modified":"2022-01-05T02:29:34","modified_gmt":"2022-01-05T02:29:34","slug":"un-millon-de-contagios-en-un-solo-dia-eu-rompe-todos-los-records-en-la-pandemia","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2022\/01\/04\/un-millon-de-contagios-en-un-solo-dia-eu-rompe-todos-los-records-en-la-pandemia\/","title":{"rendered":"Rompe EU todos los r\u00e9cords en la pandemia con un mill\u00f3n de contagios en un solo d\u00eda"},"content":{"rendered":"<p>Seg\u00fan las cifras de la universidad Johns\u00a0 Hopkins, durante las ultimas 24 hrs se han registrado. un mill\u00f3n 083 mil 948 contagios y mil 693 fallecidos lo que eleva los totales a 56 millones 191 mil 523 y 827 mil 749 respectivamente.<\/p>\n<p>MADRID, 4 Ene. (EUROPA PRESS).\u2013 Estados Unidos ha registrado este lunes m\u00e1s de un mill\u00f3n de casos de coronavirus, una cifra de contagios r\u00e9cord en todo el mundo marcada por la propagaci\u00f3n de la variante \u00d3micron, en una jornada en la que adem\u00e1s ha confirmado cerca de mil 700 muertos por COVID-19<\/p>\n<p>El n\u00famero de positivos de este lunes es casi el doble del r\u00e9cord\u00a0 anterior hace tan s\u00f3lo cuatro d\u00edas, que se fij\u00f3 en 590 mil nuevos casos, aunque esta cifra no se contar\u00e1 como un registro diario porque incluye retrasos de este fin de semana, que ha sido festivo en decenas de estados.<\/p>\n<p>Adem\u00e1s, este n\u00famero es una subestimaci\u00f3n significativa, tal y como recoge la agencia Bloomberg, porque, debido a las vacaciones navide\u00f1as, muchos estadounidenses se han hecho test de detecci\u00f3n del virus en casa, por lo que muchos de estos resultados no se han informado a las autoridades sanitarias.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan las cifras de la universidad Johns\u00a0 Hopkins, durante las ultimas 24 hrs se han registrado. un mill\u00f3n 083 mil 948 contagios y mil 693 fallecidos lo que eleva los totales a 56 millones 191 mil 523 y 827 mil 749 respectivamente. MADRID, 4 Ene. (EUROPA PRESS).\u2013 Estados Unidos ha registrado este lunes m\u00e1s de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":1185,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1184","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/1184","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1184"}],"version-history":[{"count":2,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/1184\/revisions"}],"predecessor-version":[{"id":1200,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/1184\/revisions\/1200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/1185"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1184"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1184"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1184"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}