{"id":11194,"date":"2022-08-04T00:09:07","date_gmt":"2022-08-04T00:09:07","guid":{"rendered":"http:\/\/lahora.mx\/?p=11194"},"modified":"2022-08-04T00:09:08","modified_gmt":"2022-08-04T00:09:08","slug":"un-adolescente-victima-de-secuestro-virtual-es-rescatado-en-tecamachalco","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2022\/08\/04\/un-adolescente-victima-de-secuestro-virtual-es-rescatado-en-tecamachalco\/","title":{"rendered":"Un adolescente v\u00edctima de secuestro virtual es rescatado en Tecamachalco"},"content":{"rendered":"\n<p>Como resultado de un operativo de b\u00fasqueda, la Fiscal\u00eda General del Estado de Puebla localiz\u00f3 ileso a un adolescente de 17 a\u00f1os de edad, v\u00edctima de extorsi\u00f3n en su modalidad de secuestro virtual.<\/p>\n\n\n\n<p>Se tom\u00f3 conocimiento que el 28 de julio de 2022 el padre de la v\u00edctima recibi\u00f3 la llamada telef\u00f3nica de una persona que le asegur\u00f3 tener secuestrado a su hijo, exigi\u00e9ndole que reuniera todo el dinero posible.<\/p>\n\n\n\n<p>El denunciante regres\u00f3 a su domicilio, percat\u00e1ndose que ya no estaba el adolescente por lo que solicit\u00f3 apoyo a la Instituci\u00f3n responsable de procurar justicia.<\/p>\n\n\n\n<p>Agentes investigadores iniciaron diligencias que permitieron establecer que el n\u00famero telef\u00f3nico del sujeto activo se localizaba cerca de un Centro Federal de Readaptaci\u00f3n en el estado de Tamaulipas. Asimismo, la Fiscal\u00eda de Puebla implement\u00f3 un operativo que culmin\u00f3 con la localizaci\u00f3n del afectado en \u00f3ptimas condiciones en el Centro de Tecamachalco.<\/p>\n\n\n\n<p>Ante la autoridad ministerial, el adolescente refiri\u00f3 que personas que se identificaron como integrantes de un grupo criminal se comunicaron a su domicilio indic\u00e1ndole que deb\u00eda salir de su vivienda para irse a un parque y mediante enga\u00f1os le exigieron informaci\u00f3n de sus familiares.<\/p>\n\n\n\n<p>Personal de la Fiscal\u00eda Especializada en Investigaci\u00f3n de Secuestro y Extorsi\u00f3n brind\u00f3 asesor\u00eda respecto al delito de extorsi\u00f3n en su modalidad de secuestro virtual.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como resultado de un operativo de b\u00fasqueda, la Fiscal\u00eda General del Estado de Puebla localiz\u00f3 ileso a un adolescente de 17 a\u00f1os de edad, v\u00edctima de extorsi\u00f3n en su modalidad de secuestro virtual. Se tom\u00f3 conocimiento que el 28 de julio de 2022 el padre de la v\u00edctima recibi\u00f3 la llamada telef\u00f3nica de una persona [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":11195,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[175,226],"tags":[223],"class_list":["post-11194","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","category-policia","tag-puebla"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/11194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=11194"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/11194\/revisions"}],"predecessor-version":[{"id":11196,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/11194\/revisions\/11196"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/11195"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=11194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=11194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=11194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}