{"id":10789,"date":"2022-07-27T02:49:14","date_gmt":"2022-07-27T02:49:14","guid":{"rendered":"http:\/\/lahora.mx\/?p=10789"},"modified":"2022-07-27T02:49:15","modified_gmt":"2022-07-27T02:49:15","slug":"se-reportan-152-defunciones-y-30-mil-497-contagios-en-mexico","status":"publish","type":"post","link":"https:\/\/lahora.mx\/index.php\/2022\/07\/27\/se-reportan-152-defunciones-y-30-mil-497-contagios-en-mexico\/","title":{"rendered":"Se reportan 152 defunciones y 30 mil 497 contagios en M\u00e9xico"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En un d\u00eda, los nuevos contagios por coronavirus aumentaron poco m\u00e1s de 7 veces, debido al registro de 30 mil 497 casos en las \u00faltimas 24 horas, ya que de domingo para lunes, se reportaron 4 mil 231.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por tanto, la cifra acumulada se increment\u00f3 en 6 millones 659 mil 038.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe se\u00f1alar que la mayor parte de los contagios est\u00e1n presentes en las personas de 18 a 29 a\u00f1os, seguido del grupo de 30 a 39 a\u00f1os y en tercer sitio, en la poblaci\u00f3n de 40 a 49 a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los casos activos, que son las personas positivas al virus SARS-CoV-2 que presentaron s\u00edntomas en los \u00faltimos 14 d\u00edas y que pueden contagiar, se ubicaron en 182 mil 735. Al sumar, los que est\u00e1n por confirmarse, dar\u00edan un total de 190 mil 962 casos activos estimados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su informe diario de covid-19, la Secretar\u00eda de Salud inform\u00f3 que las muertes aumentaron a 327 mil 261 por el reporte de 152 fallecimientos en las \u00faltimas 24 horas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ocupaci\u00f3n nacional hospitalaria en camas generales se mantuvo en 18% y en camas de terapia intensiva en 5%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los pacientes que se han recuperado del contagio de coronavirus son 5 millones 767 mil 724.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un d\u00eda, los nuevos contagios por coronavirus aumentaron poco m\u00e1s de 7 veces, debido al registro de 30 mil 497 casos en las \u00faltimas 24 horas, ya que de domingo para lunes, se reportaron 4 mil 231. Por tanto, la cifra acumulada se increment\u00f3 en 6 millones 659 mil 038. Cabe se\u00f1alar que la [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":10790,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[176],"tags":[195],"class_list":["post-10789","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-principal"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/10789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=10789"}],"version-history":[{"count":1,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/10789\/revisions"}],"predecessor-version":[{"id":10791,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/10789\/revisions\/10791"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media\/10790"}],"wp:attachment":[{"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=10789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=10789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=10789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}